{"id":12836,"date":"2026-05-11T16:26:18","date_gmt":"2026-05-11T14:26:18","guid":{"rendered":"https:\/\/www.hiringlab.org\/fr\/?p=12836"},"modified":"2026-05-11T16:26:18","modified_gmt":"2026-05-11T14:26:18","slug":"la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine","status":"publish","type":"post","link":"https:\/\/www.hiringlab.org\/fr\/blog\/2026\/05\/11\/la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine\/","title":{"rendered":"La transparence des salaires en Europe reste une perspective lointaine"},"content":{"rendered":"\n<p><strong>Points \u00e0 retenir :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Alors que l\u2019\u00e9ch\u00e9ance de juin 2026 pour la mise en \u0153uvre de la directive europ\u00e9enne sur la transparence salariale approche \u00e0 grands pas, la plupart des \u00c9tats membres risquent de ne pas y parvenir.<\/li>\n\n\n\n<li>L\u2019\u00e9cart entre pays europ\u00e9ens reste consid\u00e9rable&nbsp;: plus d&rsquo;une offre sur deux au Royaume-Uni mentionne le salaire, contre seulement une sur huit en Allemagne. En France, ce sont pr\u00e8s de deux offres sur cinq qui int\u00e8grent cette information.<\/li>\n\n\n\n<li>La transparence salariale progresse peu dans les grandes \u00e9conomies europ\u00e9ennes, l\u2019Italie faisant figure d\u2019exception avec une hausse notable de 22 % \u00e0 36 % en un an.<\/li>\n\n\n\n<li>Les fourchettes salariales varient fortement : l\u2019\u00e9cart m\u00e9dian de salaires horaires est de 19 % en Allemagne (p. ex. 15-17,85 \u20ac\/h), contre seulement 8 % en France (p. ex. 15-16,20 \u20ac\/h).<\/li>\n\n\n\n<li>Les offres mentionnant un salaire horaire sont les plus informatives : montant pr\u00e9cis plus fr\u00e9quent, et fourchettes plus \u00e9troites que pour les salaires mensuels ou annuels.<\/li>\n<\/ul>\n\n\n\n<p><em>Le Hiring Lab publie mensuellement des chiffres sur la transparence salariale sur le <\/em><a href=\"https:\/\/data.indeed.com\/#\/transparency\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Portail de donn\u00e9es du Hiring Lab<\/em><\/a><em>.<\/em><\/p>\n\n\n\n<p>Le salaire est <a href=\"https:\/\/www.hiringlab.org\/uk\/blog\/2025\/12\/17\/why-workers-search-pay-leads-but-meaning-matters-more-than-ever\/\" target=\"_blank\" rel=\"noreferrer noopener\">la principale raison pour laquelle les gens souhaitent changer d\u2019emploi<\/a> ; dans de nombreux pays, et notamment en Europe, cette information est pourtant tr\u00e8s souvent absente des offres d\u2019emploi. Or, la r\u00e9tention d&rsquo;informations salariales par les employeurs a des cons\u00e9quences concr\u00e8tes pour les candidats. D&rsquo;autant qu&rsquo;agir et n\u00e9gocier dans un contexte d&rsquo;asym\u00e9trie de l&rsquo;information et d&rsquo;ambigu\u00eft\u00e9 n&rsquo;a pas le <a href=\"https:\/\/www.minneapolisfed.org\/article\/2024\/pay-transparency-in-job-postings-trends-trade-offs-and-policy-design\" target=\"_blank\" rel=\"noreferrer noopener\">m\u00eame effet selon les cat\u00e9gories de travailleurs<\/a> : la litt\u00e9rature empirique <a href=\"https:\/\/www.annualreviews.org\/content\/journals\/10.1146\/annurev-economics-092022-115353#right-ref-B80\" target=\"_blank\" rel=\"noreferrer noopener\">\u00e9tablit un lien entre ces situations<\/a> et la persistance de l\u2019\u00e9cart de r\u00e9mun\u00e9ration entre les femmes et les hommes. C\u2019est dans l\u2019objectif de <a href=\"https:\/\/www.consilium.europa.eu\/fr\/policies\/pay-transparency\/\" target=\"_blank\" rel=\"noreferrer noopener\">r\u00e9duire ces in\u00e9galit\u00e9s salariales que l\u2019UE a adopt\u00e9 la directive sur la transparence salariale<\/a> en 2023. La divulgation pr\u00e9alable am\u00e9liore \u00e9galement l\u2019ad\u00e9quation des profils en donnant aux candidats la possibilit\u00e9 de <a href=\"https:\/\/store.hbr.org\/product\/research-posting-a-wide-salary-range-can-deter-women-from-applying\/H092XA\" target=\"_blank\" rel=\"noreferrer noopener\">s\u2019auto-s\u00e9lectionner en fonction d\u2019informations r\u00e9alistes<\/a>. Cependant, les donn\u00e9es du Hiring Lab montrent que les offres d\u2019emploi restent largement opaques dans la plupart des grandes \u00e9conomies europ\u00e9ennes et que les progr\u00e8s en mati\u00e8re de transparence salariale sont au point mort.<\/p>\n\n\n\n<p>Trois ans apr\u00e8s l\u2019adoption par l\u2019UE de la <a href=\"https:\/\/commission.europa.eu\/strategy-and-policy\/policies\/justice-and-fundamental-rights\/gender-equality\/equal-pay\/eu-action-equal-pay_en?prefLang=fr\" target=\"_blank\" rel=\"noreferrer noopener\">directive sur la transparence salariale<\/a> en 2023, la plupart des \u00c9tats membres, dont l\u2019Allemagne et la France, sont encore en train de l\u00e9gif\u00e9rer et manqueront probablement l\u2019\u00e9ch\u00e9ance de juin 2026 fix\u00e9e par l\u2019UE. Le calendrier parlementaire fran\u00e7ais <a href=\"https:\/\/www.publicsenat.fr\/actualites\/emploi\/transparence-salariale-dans-les-entreprises-que-va-changer-le-futur-projet-de-loi\" target=\"_blank\" rel=\"noreferrer noopener\">rend l\u2019adoption avant juin peu probable<\/a>, les Pays-Bas ont repouss\u00e9 <a href=\"https:\/\/www.rijksoverheid.nl\/documenten\/rapporten\/2026\/04\/15\/handreikingsysteemvanfunctiewaarderingenindelingloonstructuur\" target=\"_blank\" rel=\"noreferrer noopener\">la mise en \u0153uvre \u00e0 d\u00e9but 2027<\/a>. L\u2019Allemagne n\u2019a pas encore pr\u00e9sent\u00e9 de projet de loi, malgr\u00e9 le rapport d\u2019une <a href=\"https:\/\/www.bmbfsfj.bund.de\/resource\/blob\/273774\/d4fc78ee064e0245f8f4b25ae9efc3ec\/abschlussbericht-kommission-etrl-data.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">commission d\u2019experts publiant des recommandations de mise en \u0153uvre<\/a> en octobre dernier. En <a href=\"https:\/\/www.lavoro.gov.it\/stampa-e-media\/comunicati\/pagine\/trasparenza-retributiva-primo-si-del-cdm\" target=\"_blank\" rel=\"noreferrer noopener\">Italie<\/a> et en <a href=\"https:\/\/assets.gov.ie\/static\/documents\/general-scheme-of-the-equality-miscellaneous-provisions-bill-2024.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Irlande<\/a>, les projets de loi d\u00e9j\u00e0 publi\u00e9s vont plus loin que la directive concernant la transparence salariale dans les offres d\u2019emploi. Celle-ci exige que les employeurs <a href=\"https:\/\/eur-lex.europa.eu\/legal-content\/FR\/TXT\/?uri=CELEX:32023L0970\" target=\"_blank\" rel=\"noreferrer noopener\">partagent les informations sur la r\u00e9mun\u00e9ration avec les candidats avant l\u2019entretien<\/a>, sans prescrire que celle-ci soit indiqu\u00e9e dans l\u2019annonce. Ce d\u00e9tail est important car l\u2019information sur les salaires dans une annonce rend visible les \u00e9l\u00e9ments cl\u00e9s d\u2019un poste pour tous les candidats, avant m\u00eame qu\u2019ils ne consacrent du temps \u00e0 postuler. Nous identifions donc ce qui est communiqu\u00e9 dans les offres d\u2019emploi afin de mesurer la transparence r\u00e9ellement per\u00e7ue par les chercheurs d\u2019emploi lors de leur recherche.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La transparence salariale dans les offres d\u2019emploi europ\u00e9ennes est faible et stagne malgr\u00e9 les efforts l\u00e9gislatifs<\/h2>\n\n\n\n<p>Dans la plupart des grandes \u00e9conomies europ\u00e9ennes, la majorit\u00e9 des offres d\u2019emploi ne mentionnent pas la r\u00e9mun\u00e9ration. Seules 12 % des offres allemandes et 17 % des offres espagnoles indiquent le salaire&nbsp;; \u00e0 l\u2019autre extr\u00e9mit\u00e9 du spectre, le Royaume-Uni atteint 56 %, tandis que les Pays-Bas (48 %), la France (43 %), l\u2019Irlande (39 %) et l\u2019Italie (36 %) se situent entre les deux. Si la tendance \u00e0 long terme depuis 2019 est encourageante dans la plupart des pays, les donn\u00e9es des deux derni\u00e8res ann\u00e9es montrent une stagnation g\u00e9n\u00e9ralis\u00e9e. L\u2019Italie fait exception : c\u2019est le seul pays suivi \u00e0 avoir enregistr\u00e9 une progression soutenue, de 22 % \u00e0 36 % en un an. En revanche, le Royaume-Uni, qui n\u2019est pas directement concern\u00e9 par la directive europ\u00e9enne, affiche un recul de la transparence salariale : la part des offres mentionnant un salaire est pass\u00e9e de pr\u00e8s des deux tiers \u00e0 un peu plus de la moiti\u00e9. Le pays demeure n\u00e9anmoins le pays le plus transparent parmi les grandes \u00e9conomies europ\u00e9ennes. Il reste \u00e0 voir si la directive europ\u00e9enne et les l\u00e9gislations nationales auront des <a href=\"https:\/\/www.hiringlab.org\/uk\/blog\/2025\/12\/09\/indeed-2026-uk-jobs-hiring-trends-report\/#:~:text=In%202026%2C%20there,their%20UK%20postings.\" target=\"_blank\" rel=\"noreferrer noopener\">effets d\u2019entra\u00eenement sur les employeurs britanniques<\/a>, notamment ceux disposant d\u2019une pr\u00e9sence internationale.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07212430\/transpa_national_trend-1-1024x683.png\" alt=\"Graphique lin\u00e9aire intitul\u00e9 \u00ab En France, moins de la moiti\u00e9 des offres affichent un salaire \u00bb montrant la part des offres d\u2019emploi incluant des informations salariales en France, en Irlande, aux Pays-Bas, au Royaume-Uni, en Allemagne, en Italie et en Espagne.\" class=\"wp-image-12842\" srcset=\"https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07212430\/transpa_national_trend-1-1024x683.png 1024w, https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07212430\/transpa_national_trend-1-300x200.png 300w, https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07212430\/transpa_national_trend-1-768x512.png 768w, https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07212430\/transpa_national_trend-1-1536x1024.png 1536w, https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07212430\/transpa_national_trend-1-2048x1365.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Graphique lin\u00e9aire intitul\u00e9 \u00ab En France, moins de la moiti\u00e9 des offres affichent un salaire \u00bb montrant la part des offres d\u2019emploi incluant des informations salariales en France, en Irlande, aux Pays-Bas, au Royaume-Uni, en Allemagne, en Italie et en Espagne.<\/em><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">La transparence salariale frein\u00e9e par un march\u00e9 du travail moins dynamique<\/h2>\n\n\n\n<p>Les analyses du Indeed Hiring Lab sur les lois de transparence salariale au <a href=\"https:\/\/www.hiringlab.org\/en-ca\/2024\/03\/21\/salary-transparency-canadian-job-postings\/\" target=\"_blank\" rel=\"noreferrer noopener\">Canada<\/a> et aux <a href=\"https:\/\/www.hiringlab.org\/2024\/10\/23\/salary-transparency-growth-slows-but-momentum-continues\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00c9tats-Unis<\/a> montrent que les employeurs ont eu tendance \u00e0 prendre en compte les obligations de divulgation seulement \u00e0 l\u2019entr\u00e9e en vigueur des dispositifs juridiques, et non par anticipation. La situation en Europe semble similaire&nbsp;: la plupart des grands \u00c9tats membres de l\u2019UE n\u2019ayant pas encore adopt\u00e9 de l\u00e9gislation nationale, de nombreux employeurs ne semblent pas dispos\u00e9s, pour l\u2019instant, \u00e0 modifier leurs pratiques de publication d\u2019offres d\u2019emploi. Dans ce contexte, l\u2019\u00e9ch\u00e9ance de juin&nbsp;2026 fix\u00e9e par l\u2019UE constitue moins un d\u00e9clencheur imp\u00e9ratif qu\u2019un point de d\u00e9part pour des processus l\u00e9gislatifs qui se d\u00e9rouleront pour la plupart au cours des prochains mois. Certains pays pourraient aller plus loin que la directive et imposer la publication pr\u00e9alable des informations, mais en attendant, la directive autorise l\u2019omission du salaire dans les offres d\u2019emploi.<\/p>\n\n\n\n<p>La stagnation de la transparence salariale s\u2019est \u00e9galement produite dans le contexte de <a href=\"https:\/\/data.indeed.com\/#\/postings\" target=\"_blank\" rel=\"noreferrer noopener\">ralentissement de la croissance des offres d\u2019emploi sur la plupart des grands march\u00e9s europ\u00e9ens<\/a>, notamment en France, en Irlande, aux Pays-Bas et au Royaume-Uni. Le renforcement du pouvoir de n\u00e9gociation des employeurs pourrait expliquer la stagnation, voire le recul, de cette transparence. En l\u2019absence de l\u00e9gislations nationales sp\u00e9cifiques sur la transparence, l\u2019objectif g\u00e9n\u00e9ral de la directive europ\u00e9enne semble insuffisant \u00e0 lui seul pour favoriser une adoption plus large. L\u2019Italie et l\u2019Espagne font figure d\u2019exceptions notables au ralentissement du march\u00e9 du travail, avec un nombre d\u2019offres d\u2019emploi nettement sup\u00e9rieur au niveau pr\u00e9-pand\u00e9mie. En Espagne, malgr\u00e9 ce dynamisme, la transparence salariale reste faible \u2013 le ratio offres d\u2019emploi\/ch\u00f4mage y demeure bas par rapport aux autres grandes \u00e9conomies europ\u00e9ennes. En Italie, la transparence progresse : un projet de loi imposant la mention des salaires dans les offres d\u2019emploi a r\u00e9cemment \u00e9t\u00e9 publi\u00e9, et des incitations introduites sur Indeed encouragent \u00e9galement les employeurs \u00e0 renseigner cette information.<\/p>\n\n\n\n<p>Les \u00e9carts de transparence observ\u00e9s entre les pays s\u2019expliquent aussi par les institutions qui encadrent la fixation des salaires&nbsp;: au Royaume-Uni, la r\u00e9mun\u00e9ration est principalement <a href=\"https:\/\/www.oecd.org\/content\/dam\/oecd\/en\/data\/datasets\/oecd-aias-ictwss\/UnitedKingdom.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">d\u00e9termin\u00e9e au niveau de l\u2019entreprise<\/a>, alors que dans une grande partie de l\u2019Europe continentale, les salaires sont fix\u00e9s par des <a href=\"https:\/\/www.oecd.org\/en\/publications\/membership-of-unions-and-employers-organisations-and-bargaining-coverage_fe47107c-en\/full-report.html#title-7b947d66d7\" target=\"_blank\" rel=\"noreferrer noopener\">conventions collectives au niveau des secteurs d\u2019activit\u00e9<\/a>. Concr\u00e8tement, cela signifie que les salaires peuvent fr\u00e9quemment \u00eatre estim\u00e9s \u00e0 partir de grilles salariales rendues publiques. Le faible niveau de transparence en Allemagne \u00e9taye cette observation&nbsp;: les salaires \u00e9tant largement r\u00e9gis par des conventions collectives, les employeurs individuels sont peu incit\u00e9s \u00e0 divulguer les fourchettes de salaires dans les offres d\u2019emploi. En effet, la directive europ\u00e9enne autorise sp\u00e9cifiquement la mise \u00e0 disposition des informations salariales aux candidats par les <a href=\"https:\/\/eur-lex.europa.eu\/legal-content\/FR\/TXT\/?uri=CELEX:32023L0970#:~:text=Les%20informations%20devraient%20%C3%AAtre%20fournies%20par%20l%E2%80%99employeur%20ou%20par%20un%20autre%20canal%2C%20par%20exemple%20par%20les%20partenaires%20sociaux.\" target=\"_blank\" rel=\"noreferrer noopener\">partenaires sociaux<\/a> (par exemple, les syndicats).<\/p>\n\n\n\n<p>Par ailleurs, la transparence salariale dans les offres d\u2019emploi est un pr\u00e9f\u00e9rence d\u00e9clar\u00e9e des chercheurs d\u2019emploi et des travailleurs europ\u00e9ens, selon une enqu\u00eate men\u00e9e pour Indeed. Une large majorit\u00e9 des personnes interrog\u00e9es dans l\u2019ensemble des pays \u00e9tudi\u00e9s (entre 61&nbsp;% en Allemagne, 66&nbsp;% en France et 82&nbsp;% en Irlande) d\u00e9clarent qu\u2019elles seraient plus enclines \u00e0 postuler \u00e0 une offre d\u2019emploi indiquant une fourchette salariale, et une proportion encore plus \u00e9lev\u00e9e (64 %, 74&nbsp;% et 83 % respectivement) estiment que ces fourchettes devraient \u00eatre syst\u00e9matiquement mentionn\u00e9es. Fait notable, les femmes sont plus nombreuses que les hommes \u00e0 partager ces deux opinions, ce qui renforce l\u2019id\u00e9e que la transparence salariale pourrait contribuer \u00e0 r\u00e9duire les \u00e9carts entre les sexes, notamment en mati\u00e8re de candidatures et de <a href=\"https:\/\/psycnet.apa.org\/buy\/2017-56124-001\" target=\"_blank\" rel=\"noreferrer noopener\">n\u00e9gociation dans des contextes d\u2019incertitude<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07212611\/survey_salary_preferences-1-1024x683.png\" alt=\"Graphique \u00e0 barres intitul\u00e9 \u00ab Les chercheurs d\u2019emploi europ\u00e9ens souhaitent la transparence salariale \u00bb montrant la part des r\u00e9pondants \u00e0 l\u2019enqu\u00eate qui d\u00e9clarent \u00eatre d\u2019accord avec les \u00e9nonc\u00e9s \u00ab\u00a0Je serais plus susceptible de postuler \u00e0 une offre si elle indiquait la fourchette salariale\u00a0\u00bb et \u00ab\u00a0Les offres d\u2019emploi devraient inclure les fourchettes salariales par d\u00e9faut\u00a0\u00bb.\" class=\"wp-image-12843\" srcset=\"https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07212611\/survey_salary_preferences-1-1024x683.png 1024w, https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07212611\/survey_salary_preferences-1-300x200.png 300w, https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07212611\/survey_salary_preferences-1-768x512.png 768w, https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07212611\/survey_salary_preferences-1-1536x1024.png 1536w, https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07212611\/survey_salary_preferences-1-2048x1365.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Graphique \u00e0 barres intitul\u00e9 \u00ab Les chercheurs d\u2019emploi europ\u00e9ens souhaitent la transparence salariale \u00bb montrant la part des r\u00e9pondants \u00e0 l\u2019enqu\u00eate qui d\u00e9clarent \u00eatre d\u2019accord avec les \u00e9nonc\u00e9s \u00ab&nbsp;Je serais plus susceptible de postuler \u00e0 une offre si elle indiquait la fourchette salariale&nbsp;\u00bb et \u00ab&nbsp;Les offres d\u2019emploi devraient inclure les fourchettes salariales par d\u00e9faut&nbsp;\u00bb.<\/em><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Les emplois les moins bien r\u00e9mun\u00e9r\u00e9s ont tendance \u00e0 \u00eatre plus transparents<\/h2>\n\n\n\n<p>Les taux de transparence varient consid\u00e9rablement selon les familles de m\u00e9tiers. Les cat\u00e9gories les plus transparentes regroupent g\u00e9n\u00e9ralement les emplois standardis\u00e9s et peu r\u00e9mun\u00e9r\u00e9s, tels que le nettoyage et l\u2019assainissement en Allemagne, le transport routier en Espagne et en Italie, les soins personnels et m\u00e9dicaux \u00e0 domicile au Royaume-Uni et en France, la pu\u00e9riculture en Irlande et les services de proximit\u00e9 aux Pays-Bas. Ces emplois se caract\u00e9risent par un fort turnover du personnel, une plus grande substituabilit\u00e9 de la main-d\u2019\u0153uvre et <a href=\"https:\/\/www.sciencedirect.com\/science\/article\/abs\/pii\/S092753710400079X\" target=\"_blank\" rel=\"noreferrer noopener\">moins d\u2019avantages non salariaux<\/a> : le salaire constitue ainsi l\u2019un des principaux crit\u00e8res de diff\u00e9renciation entre les employeurs.&nbsp;<\/p>\n\n\n\n<p>S\u00e9lectionnez un pays pour afficher les taux de transparence salariale des offres d\u2019emploi par famille de m\u00e9tiers&nbsp;:<\/p>\n\n\n<style>\n       .errordiv { padding:10px; margin:10px; border: 1px solid #555555;color: #000000;background-color: #f8f8f8; width:500px; }#advanced_iframe {visibility:visible;opacity:1;vertical-align:top;}.ai-info-bottom-iframe { position: fixed; z-index: 10000; bottom:0; left: 0; margin: 0px; text-align: center; width: 100%; background-color: #ff9999; padding-left: 5px;padding-bottom: 5px; border-top: 1px solid #aaa } a.ai-bold {font-weight: bold;}#ai-layer-div-advanced_iframe p {height:100%;margin:0;padding:0}<\/style><script type=\"text\/javascript\">var ai_iframe_width_advanced_iframe = 0;var ai_iframe_height_advanced_iframe = 0;function aiReceiveMessageadvanced_iframe(event) {  aiProcessMessage(event,\"advanced_iframe\", \"true\",\"\",\"false\",\"false\");}if (window.addEventListener) {  window.addEventListener(\"message\", aiReceiveMessageadvanced_iframe);} else if (el.attachEvent)  {  el.attachEvent(\"message\", aiReceiveMessageadvanced_iframe);}var aiOnloadScrollTop=\"true\";var aiShowDebug=false;\n\t\tif (typeof aiReadyCallbacks === 'undefined') {\n\t\t\tvar aiReadyCallbacks = [];\n\t\t} else if (!(aiReadyCallbacks instanceof Array)) {\n\t\t\tvar aiReadyCallbacks = [];\n\t\t}    function aiShowIframeId(id_iframe) { jQuery(\"#\"+id_iframe).css(\"visibility\", \"visible\");    }    function aiResizeIframeHeight(height) { aiResizeIframeHeight(height,advanced_iframe); }    function aiResizeIframeHeightId(height,width,id) {aiResizeIframeHeightById(id,height);}<\/script><iframe id=\"advanced_iframe\"  name=\"advanced_iframe\"  src=\"https:\/\/hiring-lab.github.io\/pages\/eu-transparency-2026\/html\/transpa_normcat_paytype_fr.html\"  width=\"779\"  height=\"1250\"  frameborder=\"0\"  border=\"0\"  allowtransparency=\"true\"  loading=\"lazy\"  style=\";border-width: 0px;;border: none;;width:779px;;height:1250px;\" ><\/iframe><script type=\"text\/javascript\">var ifrm_advanced_iframe = document.getElementById(\"advanced_iframe\");var hiddenTabsDoneadvanced_iframe = false;\nfunction resizeCallbackadvanced_iframe() {}<\/script><script type=\"text\/javascript\"><\/script><p style=\"display:block !important; visibility:visible !important;margin: -18px 14px 0 0;padding-left: 3px;padding-top:3px;background: white; overflow: hidden; position: relative; line-height:15px;width: fit-content;\"><small style=\"display:block !important;visibility:visible !important\">powered by Advanced iFrame<\/small><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Dans la plupart des pays, les cat\u00e9gories professionnelles o\u00f9 la r\u00e9mun\u00e9ration horaire est la norme \u2013 souvent des emplois peu r\u00e9mun\u00e9r\u00e9s et non permanents \u2013 affichent g\u00e9n\u00e9ralement des taux de transparence plus \u00e9lev\u00e9s que celles o\u00f9 le salaire annuel pr\u00e9domine. Cette tendance se v\u00e9rifie nettement au Royaume-Uni, en Allemagne, en France et, dans une moindre mesure, en Italie. Les Pays-Bas font exception&nbsp;: les salaires dans les offres d\u2019emploi y sont majoritairement exprim\u00e9s en salaire mensuel, et les cat\u00e9gories professionnelles o\u00f9 la r\u00e9mun\u00e9ration horaire est dominante ne sont pas pour autant plus transparentes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les chiffres pr\u00e9cis sont l\u2019exception ; les fourchettes de salaires sont la r\u00e8gle<\/h2>\n\n\n\n<p>Parmi les offres d\u2019emploi contenant de l\u2019information salariale, rares sont celles qui indiquent un montant pr\u00e9cis&nbsp;; la grande majorit\u00e9 se contentent d\u2019indiquer une fourchette ou une limite sup\u00e9rieure ou inf\u00e9rieure. Les montants pr\u00e9cis sont les plus fr\u00e9quents au Royaume-Uni (32&nbsp;% des offres), suivi de l\u2019Espagne et de la France (24&nbsp;%). C\u2019est en Italie (10&nbsp;%) et aux Pays-Bas (8&nbsp;%) que les offres d\u2019emploi mentionnant un salaire sont les moins susceptibles d\u2019afficher un montant pr\u00e9cis.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07212835\/transpa_disclosure_snapshot-1-1024x683.png\" alt=\"Graphique \u00e0 barres empil\u00e9es intitul\u00e9 \u00ab\u00a0Les chiffres pr\u00e9cis sont l\u2019exception, les fourchettes salariales la r\u00e8gle\u00a0\u00bb montrant la r\u00e9partition des offres d\u2019emploi transparentes en mati\u00e8re de salaire selon le format de divulgation du salaire dans chaque pays.\" class=\"wp-image-12844\" srcset=\"https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07212835\/transpa_disclosure_snapshot-1-1024x683.png 1024w, https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07212835\/transpa_disclosure_snapshot-1-300x200.png 300w, https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07212835\/transpa_disclosure_snapshot-1-768x512.png 768w, https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07212835\/transpa_disclosure_snapshot-1-1536x1024.png 1536w, https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07212835\/transpa_disclosure_snapshot-1-2048x1365.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Graphique \u00e0 barres empil\u00e9es intitul\u00e9 \u00ab&nbsp;Les chiffres pr\u00e9cis sont l\u2019exception, les fourchettes salariales la r\u00e8gle&nbsp;\u00bb montrant la r\u00e9partition des offres d\u2019emploi transparentes en mati\u00e8re de salaire selon le format de divulgation du salaire dans chaque pays.<\/em><\/figcaption><\/figure>\n\n\n\n<p>La pr\u00e9cision varie \u00e9galement selon le type de r\u00e9mun\u00e9ration propos\u00e9. Le salaire horaire est plus souvent indiqu\u00e9 sous forme de montant pr\u00e9cis et, lorsqu\u2019une fourchette est mentionn\u00e9e, elle est g\u00e9n\u00e9ralement plus resserr\u00e9e. En Espagne, par exemple, 53 % des offres de salaire horaire mentionnent un chiffre pr\u00e9cis, contre seulement 21 % pour les offres de salaire annuel. Cette tendance se confirme dans tous les pays \u00e9tudi\u00e9s, m\u00eame si l\u2019\u00e9cart entre les types de r\u00e9mun\u00e9ration varie.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"853\" src=\"https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07212920\/transpa_precise_range_by_salarytype-1-1024x853.png\" alt=\"Graphique en halt\u00e8re intitul\u00e9 \u00ab Les salaires horaires sont plus souvent indiqu\u00e9s sous forme de montant pr\u00e9cis \u00bb montrant la part des offres d\u2019emploi avec des salaires mentionnant un montant exact plut\u00f4t qu\u2019une fourchette ou une limite sup\u00e9rieure\/inf\u00e9rieure, par pays et par type de salaire.\" class=\"wp-image-12845\" srcset=\"https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07212920\/transpa_precise_range_by_salarytype-1-1024x853.png 1024w, https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07212920\/transpa_precise_range_by_salarytype-1-300x250.png 300w, https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07212920\/transpa_precise_range_by_salarytype-1-768x640.png 768w, https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07212920\/transpa_precise_range_by_salarytype-1-1536x1280.png 1536w, https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07212920\/transpa_precise_range_by_salarytype-1.png 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Graphique en halt\u00e8re intitul\u00e9 \u00ab Les salaires horaires sont plus souvent indiqu\u00e9s sous forme de montant pr\u00e9cis \u00bb montrant la part des offres d\u2019emploi avec des salaires mentionnant un montant exact plut\u00f4t qu\u2019une fourchette ou une limite sup\u00e9rieure\/inf\u00e9rieure, par pays et par type de salaire.<\/em><\/figcaption><\/figure>\n\n\n\n<p>Les offres d\u2019emploi affichant une information salariale indiquent g\u00e9n\u00e9ralement une fourchette plut\u00f4t qu\u2019un montant fixe, refl\u00e9tant le fait que la r\u00e9mun\u00e9ration finale est d\u00e9termin\u00e9e en fonction de l\u2019exp\u00e9rience et des comp\u00e9tences du candidat, ainsi qu\u2019en fonction de la&nbsp; n\u00e9gociation entre celui-ci et l\u2019employeur. Les fourchettes m\u00e9dianes varient fortement selon les pays et les types de r\u00e9mun\u00e9ration : en France, la fourchette horaire m\u00e9diane est de 8 % (p. ex. 15-16,20 \u20ac\/h), tandis que les fourchettes annuelles sont plus larges, \u00e0 19 % (p. ex. 35 000-41 650 \u20ac). Les fourchettes de salaires horaires sont g\u00e9n\u00e9ralement plus \u00e9troites que celles des r\u00e9mun\u00e9rations mensuelles ou annuelles, \u00e0 l\u2019exception de l\u2019Espagne, o\u00f9 les salaires horaires sont indiqu\u00e9s avec un peu moins de pr\u00e9cision. \u00c0 l\u2019inverse, l\u2019Italie pr\u00e9sente les fourchettes les plus larges de l\u2019\u00e9chantillon \u2013 avec une m\u00e9diane de 50 % au-dessus du minimum indiqu\u00e9, une offre \u00e0 3 000 \u20ac\/mois plafonnerait typiquement \u00e0 4 500 \u20ac.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"922\" height=\"1024\" src=\"https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07213006\/transpa_range_by_salarytype-1-922x1024.png\" alt=\"Graphique \u00e0 barres intitul\u00e9 \u00ab Les offres r\u00e9mun\u00e9r\u00e9es \u00e0 l\u2019heure affichent g\u00e9n\u00e9ralement des fourchettes salariales plus \u00e9troites \u00bb, pr\u00e9sentant la fourchette salariale m\u00e9diane, exprim\u00e9e en pourcentage de la limite inf\u00e9rieure, dans les offres d\u2019emploi contenant des informations sur la r\u00e9mun\u00e9ration. Ventilation par pays par type de salaire affich\u00e9 (horaire, mensuel ou annuel).\" class=\"wp-image-12846\" srcset=\"https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07213006\/transpa_range_by_salarytype-1-922x1024.png 922w, https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07213006\/transpa_range_by_salarytype-1-270x300.png 270w, https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07213006\/transpa_range_by_salarytype-1-768x853.png 768w, https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07213006\/transpa_range_by_salarytype-1-1382x1536.png 1382w, https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07213006\/transpa_range_by_salarytype-1-1843x2048.png 1843w\" sizes=\"auto, (max-width: 922px) 100vw, 922px\" \/><figcaption class=\"wp-element-caption\"><em><em>Graphique \u00e0 barres intitul\u00e9 \u00ab Les offres r\u00e9mun\u00e9r\u00e9es \u00e0 l\u2019heure affichent g\u00e9n\u00e9ralement des fourchettes salariales plus \u00e9troites \u00bb, pr\u00e9sentant la fourchette salariale m\u00e9diane, exprim\u00e9e en pourcentage de la limite inf\u00e9rieure, dans les offres d\u2019emploi contenant des informations sur la r\u00e9mun\u00e9ration. Ventilation par pays par type de salaire affich\u00e9 (horaire, mensuel ou annuel).<\/em><\/em><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusion<\/h2>\n\n\n\n<p>Sans obligation l\u00e9gale nationale, les employeurs europ\u00e9ens ne devraient pas modifier spontan\u00e9ment leurs pratiques de transparence salariale. Et m\u00eame alors, la qualit\u00e9 des informations divulgu\u00e9es n\u2019est pas garantie&nbsp;: certains employeurs pourraient r\u00e9agir en affichant des fourchettes salariales suffisamment larges pour se conformer \u00e0 la loi, sans pour autant r\u00e9v\u00e9ler grand-chose sur la r\u00e9mun\u00e9ration r\u00e9elle. Pour l\u2019instant, les donn\u00e9es r\u00e9v\u00e8lent combien les chercheurs d\u2019emploi europ\u00e9ens manquent d\u2019informations sur les salaires des postes auxquels ils postulent. \u00c0 mesure que les l\u00e9gislations nationales entreront en vigueur, ce rapport constituera une base de r\u00e9f\u00e9rence pour mesurer les progr\u00e8s de la transparence salariale en Europe.<\/p>\n\n\n\n<p><strong>M\u00e9thodologie<\/strong><\/p>\n\n\n\n<p><em>Nous calculons la transparence salariale des offres d\u2019emploi en divisant le nombre d\u2019offres d\u2019emploi uniques affichant un salaire par le nombre total d\u2019annonces uniques publi\u00e9es au cours d\u2019un mois donn\u00e9. Les informations salariales sont extraites des annonces publi\u00e9es ou index\u00e9es par les employeurs sur Indeed. Certaines offres font r\u00e9f\u00e9rence \u00e0 des points de r\u00e9f\u00e9rence publics tels que le salaire minimum ou les bar\u00e8mes salariaux issus des conventions collectives plut\u00f4t que de citer explicitement les chiffres&nbsp;; inclure ces cas ne modifie pas de mani\u00e8re significative la proportion ni les tendances en mati\u00e8re de transparence salariale.<\/em><\/p>\n\n\n\n<p><em>L\u2019enqu\u00eate Indeed\/Censuswide sur les pr\u00e9f\u00e9rences en mati\u00e8re de transparence salariale a \u00e9t\u00e9 men\u00e9e en janvier 2025 aupr\u00e8s de 6011 travailleurs et demandeurs d\u2019emploi \u00e2g\u00e9s de 18 ans ou plus au Royaume-Uni, aux Pays-Bas, en France, en Italie, en Allemagne et en Irlande.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trois ans apr\u00e8s l\u2019adoption par l\u2019UE de sa directive sur la transparence salariale, la plupart des offres d\u2019emploi europ\u00e9ennes ne mentionnent toujours pas le salaire, obligeant les candidats \u00e0 postuler avec une connaissance imparfaite de la r\u00e9mun\u00e9ration.<\/p>\n","protected":false},"author":103,"featured_media":12847,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"recruiter-hub-blocks.php","format":"standard","meta":{"_acf_changed":true,"footnotes":""},"categories":[1],"tags":[150],"post_mwm_category":[],"post_topic":[],"post_content_type":[],"post_duration":[],"post_actions":[],"post_franchise":[],"post_mwm_author":[246],"class_list":["post-12836","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-spotlight","post_mwm_author-lfeist"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La transparence des salaires en Europe reste une perspective lointaine - Indeed Hiring Lab France<\/title>\n<meta name=\"description\" content=\"Trois ans apr\u00e8s l\u2019adoption par l\u2019UE de sa directive sur la transparence salariale, la plupart des offres d\u2019emploi europ\u00e9ennes ne mentionnent toujours pas le salaire, obligeant les candidats \u00e0 postuler avec une connaissance imparfaite de la r\u00e9mun\u00e9ration.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hiringlab.org\/fr\/blog\/2026\/05\/11\/la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La transparence des salaires en Europe reste une perspective lointaine - Indeed Hiring Lab France\" \/>\n<meta property=\"og:description\" content=\"Trois ans apr\u00e8s l\u2019adoption par l\u2019UE de sa directive sur la transparence salariale, la plupart des offres d\u2019emploi europ\u00e9ennes ne mentionnent toujours pas le salaire, obligeant les candidats \u00e0 postuler avec une connaissance imparfaite de la r\u00e9mun\u00e9ration.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hiringlab.org\/fr\/blog\/2026\/05\/11\/la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine\/\" \/>\n<meta property=\"og:site_name\" content=\"Indeed Hiring Lab France\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-11T14:26:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07213433\/Office_Workspaces_twopeoplediscussingonacouch-getty20--scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1731\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lisa Feist\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2026\\\/05\\\/11\\\/la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2026\\\/05\\\/11\\\/la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine\\\/\"},\"author\":{\"name\":\"ltheissen\",\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/#\\\/schema\\\/person\\\/4b5c7a64267b1cb495fb45e90277f353\"},\"headline\":\"La transparence des salaires en Europe reste une perspective lointaine\",\"datePublished\":\"2026-05-11T14:26:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2026\\\/05\\\/11\\\/la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine\\\/\"},\"wordCount\":2667,\"image\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2026\\\/05\\\/11\\\/la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d341ezm4iqaae0.cloudfront.net\\\/hiringlaborg\\\/sites\\\/4\\\/2026\\\/05\\\/07213433\\\/Office_Workspaces_twopeoplediscussingonacouch-getty20--scaled.jpg\",\"keywords\":[\"Spotlight\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2026\\\/05\\\/11\\\/la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine\\\/\",\"url\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2026\\\/05\\\/11\\\/la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine\\\/\",\"name\":\"La transparence des salaires en Europe reste une perspective lointaine - Indeed Hiring Lab France\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2026\\\/05\\\/11\\\/la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2026\\\/05\\\/11\\\/la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d341ezm4iqaae0.cloudfront.net\\\/hiringlaborg\\\/sites\\\/4\\\/2026\\\/05\\\/07213433\\\/Office_Workspaces_twopeoplediscussingonacouch-getty20--scaled.jpg\",\"datePublished\":\"2026-05-11T14:26:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/#\\\/schema\\\/person\\\/4b5c7a64267b1cb495fb45e90277f353\"},\"description\":\"Trois ans apr\u00e8s l\u2019adoption par l\u2019UE de sa directive sur la transparence salariale, la plupart des offres d\u2019emploi europ\u00e9ennes ne mentionnent toujours pas le salaire, obligeant les candidats \u00e0 postuler avec une connaissance imparfaite de la r\u00e9mun\u00e9ration.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2026\\\/05\\\/11\\\/la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2026\\\/05\\\/11\\\/la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2026\\\/05\\\/11\\\/la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/d341ezm4iqaae0.cloudfront.net\\\/hiringlaborg\\\/sites\\\/4\\\/2026\\\/05\\\/07213433\\\/Office_Workspaces_twopeoplediscussingonacouch-getty20--scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/d341ezm4iqaae0.cloudfront.net\\\/hiringlaborg\\\/sites\\\/4\\\/2026\\\/05\\\/07213433\\\/Office_Workspaces_twopeoplediscussingonacouch-getty20--scaled.jpg\",\"width\":2560,\"height\":1731,\"caption\":\"Deux coll\u00e8gues discutent de mani\u00e8re informelle sur un canap\u00e9 dans un espace de travail moderne et lumineux.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2026\\\/05\\\/11\\\/la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La transparence des salaires en Europe reste une perspective lointaine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/\",\"name\":\"Indeed Hiring Lab France\",\"description\":\"Just another Wordpress Admins Site Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/#\\\/schema\\\/person\\\/4b5c7a64267b1cb495fb45e90277f353\",\"name\":\"ltheissen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6367a954a4c7eb916945e225eca8caf2ceb055d42150b6a655ede10de2750ac2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6367a954a4c7eb916945e225eca8caf2ceb055d42150b6a655ede10de2750ac2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6367a954a4c7eb916945e225eca8caf2ceb055d42150b6a655ede10de2750ac2?s=96&d=mm&r=g\",\"caption\":\"ltheissen\"},\"url\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/author\\\/ltheissen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La transparence des salaires en Europe reste une perspective lointaine - Indeed Hiring Lab France","description":"Trois ans apr\u00e8s l\u2019adoption par l\u2019UE de sa directive sur la transparence salariale, la plupart des offres d\u2019emploi europ\u00e9ennes ne mentionnent toujours pas le salaire, obligeant les candidats \u00e0 postuler avec une connaissance imparfaite de la r\u00e9mun\u00e9ration.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hiringlab.org\/fr\/blog\/2026\/05\/11\/la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine\/","og_locale":"fr_FR","og_type":"article","og_title":"La transparence des salaires en Europe reste une perspective lointaine - Indeed Hiring Lab France","og_description":"Trois ans apr\u00e8s l\u2019adoption par l\u2019UE de sa directive sur la transparence salariale, la plupart des offres d\u2019emploi europ\u00e9ennes ne mentionnent toujours pas le salaire, obligeant les candidats \u00e0 postuler avec une connaissance imparfaite de la r\u00e9mun\u00e9ration.","og_url":"https:\/\/www.hiringlab.org\/fr\/blog\/2026\/05\/11\/la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine\/","og_site_name":"Indeed Hiring Lab France","article_published_time":"2026-05-11T14:26:18+00:00","og_image":[{"width":2560,"height":1731,"url":"https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07213433\/Office_Workspaces_twopeoplediscussingonacouch-getty20--scaled.jpg","type":"image\/jpeg"}],"author":"Lisa Feist","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2026\/05\/11\/la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine\/#article","isPartOf":{"@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2026\/05\/11\/la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine\/"},"author":{"name":"ltheissen","@id":"https:\/\/www.hiringlab.org\/fr\/#\/schema\/person\/4b5c7a64267b1cb495fb45e90277f353"},"headline":"La transparence des salaires en Europe reste une perspective lointaine","datePublished":"2026-05-11T14:26:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2026\/05\/11\/la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine\/"},"wordCount":2667,"image":{"@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2026\/05\/11\/la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine\/#primaryimage"},"thumbnailUrl":"https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07213433\/Office_Workspaces_twopeoplediscussingonacouch-getty20--scaled.jpg","keywords":["Spotlight"],"articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2026\/05\/11\/la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine\/","url":"https:\/\/www.hiringlab.org\/fr\/blog\/2026\/05\/11\/la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine\/","name":"La transparence des salaires en Europe reste une perspective lointaine - Indeed Hiring Lab France","isPartOf":{"@id":"https:\/\/www.hiringlab.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2026\/05\/11\/la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine\/#primaryimage"},"image":{"@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2026\/05\/11\/la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine\/#primaryimage"},"thumbnailUrl":"https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07213433\/Office_Workspaces_twopeoplediscussingonacouch-getty20--scaled.jpg","datePublished":"2026-05-11T14:26:18+00:00","author":{"@id":"https:\/\/www.hiringlab.org\/fr\/#\/schema\/person\/4b5c7a64267b1cb495fb45e90277f353"},"description":"Trois ans apr\u00e8s l\u2019adoption par l\u2019UE de sa directive sur la transparence salariale, la plupart des offres d\u2019emploi europ\u00e9ennes ne mentionnent toujours pas le salaire, obligeant les candidats \u00e0 postuler avec une connaissance imparfaite de la r\u00e9mun\u00e9ration.","breadcrumb":{"@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2026\/05\/11\/la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hiringlab.org\/fr\/blog\/2026\/05\/11\/la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2026\/05\/11\/la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine\/#primaryimage","url":"https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07213433\/Office_Workspaces_twopeoplediscussingonacouch-getty20--scaled.jpg","contentUrl":"https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2026\/05\/07213433\/Office_Workspaces_twopeoplediscussingonacouch-getty20--scaled.jpg","width":2560,"height":1731,"caption":"Deux coll\u00e8gues discutent de mani\u00e8re informelle sur un canap\u00e9 dans un espace de travail moderne et lumineux."},{"@type":"BreadcrumbList","@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2026\/05\/11\/la-transparence-des-salaires-en-europe-reste-une-perspective-lointaine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hiringlab.org\/fr\/"},{"@type":"ListItem","position":2,"name":"La transparence des salaires en Europe reste une perspective lointaine"}]},{"@type":"WebSite","@id":"https:\/\/www.hiringlab.org\/fr\/#website","url":"https:\/\/www.hiringlab.org\/fr\/","name":"Indeed Hiring Lab France","description":"Just another Wordpress Admins Site Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hiringlab.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.hiringlab.org\/fr\/#\/schema\/person\/4b5c7a64267b1cb495fb45e90277f353","name":"ltheissen","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/6367a954a4c7eb916945e225eca8caf2ceb055d42150b6a655ede10de2750ac2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6367a954a4c7eb916945e225eca8caf2ceb055d42150b6a655ede10de2750ac2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6367a954a4c7eb916945e225eca8caf2ceb055d42150b6a655ede10de2750ac2?s=96&d=mm&r=g","caption":"ltheissen"},"url":"https:\/\/www.hiringlab.org\/fr\/blog\/author\/ltheissen\/"}]}},"_links":{"self":[{"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/posts\/12836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/users\/103"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/comments?post=12836"}],"version-history":[{"count":0,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/posts\/12836\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/media\/12847"}],"wp:attachment":[{"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/media?parent=12836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/categories?post=12836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/tags?post=12836"},{"taxonomy":"post_mwm_category","embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/post_mwm_category?post=12836"},{"taxonomy":"post_topic","embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/post_topic?post=12836"},{"taxonomy":"post_content_type","embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/post_content_type?post=12836"},{"taxonomy":"post_duration","embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/post_duration?post=12836"},{"taxonomy":"post_actions","embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/post_actions?post=12836"},{"taxonomy":"post_franchise","embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/post_franchise?post=12836"},{"taxonomy":"post_mwm_author","embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/post_mwm_author?post=12836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}