{"id":11447,"date":"2020-09-04T16:01:44","date_gmt":"2020-09-04T14:01:44","guid":{"rendered":"https:\/\/www.hiringlab.org\/fr\/?p=11447"},"modified":"2020-09-04T16:01:44","modified_gmt":"2020-09-04T14:01:44","slug":"marche-du-travail-se-transforme-coronavirus","status":"publish","type":"post","link":"https:\/\/www.hiringlab.org\/fr\/blog\/2020\/09\/04\/marche-du-travail-se-transforme-coronavirus\/","title":{"rendered":"Le march\u00e9 du travail se transforme  sous l\u2019effet de la crise du coronavirus"},"content":{"rendered":"\n<p>La comparaison des flux de nouvelles offres avant, pendant et apr\u00e8s la crise permet de mettre en \u00e9vidence la progression des m\u00e9tiers de la propret\u00e9, de l\u2019hygi\u00e8ne et les services \u00e0 la personne, alors que l\u2019industrie d\u00e9cline. Si le secteur de la propret\u00e9 \u00ab b\u00e9n\u00e9ficie \u00bb directement de la situation sanitaire, l\u2019essor des services \u00e0 la personne s\u2019inscrit quant \u00e0 lui dans une tendance plus large d\u2019\u00e9volution des modes de vie et d\u2019organisation des foyers que la pand\u00e9mie aura contribu\u00e9 \u00e0 acc\u00e9l\u00e9rer.<\/p>\n\n\n\n<p>Comme nous le soulignons lors de nos point r\u00e9guliers concernant le march\u00e9 du travail dans la crise, le flux de nouvelles offres d\u2019emploi est revenu au niveau des ann\u00e9es pr\u00e9c\u00e9dentes, apr\u00e8s avoir touch\u00e9 un point bas le 19 avril, au milieu du confinement. Le flux global de nouvelles offres comptabilis\u00e9es sur Indeed n\u2019\u00e9tait alors qu\u2019\u00e0 32 % de son niveau du 1er f\u00e9vrier, date que nous prenons comme r\u00e9f\u00e9rence depuis le d\u00e9but de la crise.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/6EQK5uKZRUgP4_t28kGo4CIel8Ke5Tz9kHdLzY2PUFZZjdfUDNio2IMUNdqVHTUToyWqXA5rci6h_0uVayUJzkq48ZyTnYGQLBRcFokBaVcwGHrIAOAUSvJcHH2sSDQPOUob8qQf\" alt=\"Nouvelles annonces d'emploi en France\" \/><figcaption>Le graphique en courbes illustre la moyenne mobile sur 7 jours des annonces d&#8217;emploi en France. L&rsquo;axe vertical indique la moyenne, commen\u00e7ant \u00e0 100 au 1er f\u00e9vrier. L&rsquo;axe horizontal indique les mois, du 1er f\u00e9vrier au 1er ao\u00fbt, le dernier point indiqu\u00e9 \u00e9tant le 28 ao\u00fbt. Les courbes individuelles repr\u00e9sentent les ann\u00e9es : 2018, 2019 et 2020. La source des donn\u00e9es est Indeed. Les nouveaux postes vacants sont d\u00e9finis comme les postes vacants publi\u00e9s sur Indeed pendant 7 jours ou moins.<\/figcaption><\/figure>\n\n\n\n<p>Au-del\u00e0 des \u00e9volutions hebdomadaires, la comparaison sur plusieurs semaines de la d\u00e9composition en familles de m\u00e9tiers de ce flux d\u2019offre apporte des enseignements \u00e9clairants. depuis le point bas du 19 avril, l\u2019augmentation des nouvelles annonces dans le secteur de la propret\u00e9 et de l\u2019hygi\u00e8ne et de la garde d\u2019enfants est particuli\u00e8rement notable. Ces deux secteurs ont vu leur part dans le total augmenter de plus de 3 points de pourcentage. \u00c0 l\u2019inverse, les soins infirmiers affichent une baisse de plus de 5 points, ais\u00e9ment explicable par les besoins tr\u00e8s importants dans le secteur alors que la premi\u00e8re vague s\u00e9vissait ; une \u00e9volution en miroir de celle du secteur de la restauration, qui effectue un rebond par rapport \u00e0 une p\u00e9riode o\u00f9 les restaurants \u00e9taient sous le coup d\u2019une obligation de fermeture administrative pour juguler la pand\u00e9mie. Les m\u00e9tiers de la vente et du transport ont \u00e9galement vu leur part augmenter dans le total des offres.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/QjHeuYQmqvE3E2uY6sjXiQRtEN8coU53nt0RJU3CoJdT0uBbjs9FXoYbCDLZCflIBWq69bNz_XCym1fgTHcFcKHoJg978EO-VQ2qS6U2RtjdcdOo_lhNdap1kUYAr2x_Is-td4R4\" alt=\"Secteurs en pointe de la reprise depuis le confinement\" \/><figcaption>Le tableau en deux parties illustre la variation de la part des nouvelles offres d&#8217;emploi par rapport au 19 avril, date du point bas des nouvelles offres. La premi\u00e8re partie du tableau liste les m\u00e9tiers dont la part a augment\u00e9 et leur variation en points de pourcentage. De haut en bas : Propret\u00e9 et hygi\u00e8ne 4,2 ; Garde d&rsquo;enfants 3,5 ; Restauration 2,3 ; Vente et prospection commerciale 1,5 ; Soins personnels et \u00e0 domicile 1,4 ; Transport et logistique 0,7 ; Vente au d\u00e9tail 0,6 ; Transport routier 0,3 ; M\u00e9decine 0,2 ; Magasinage et entreposage 0,1. La deuxi\u00e8me partie du tableau liste les m\u00e9tiers dont la part a diminu\u00e9 et leur variation en points de pourcentage. De haut en bas : Soins infirmiers -5,2 ; Management -1,6 ; Comptabilit\u00e9 -1,4 ; Enseignement et formation -1,2 ; Production et fabrication -1,2 ; Ing\u00e9nierie industrielle -1,2 ; D\u00e9veloppement de logiciels -1,1 ; Gestion de projet -0,7 ; Immobilier -0,6 ; Maintenance et r\u00e9paration -0,6. La source des donn\u00e9es est Indeed.<\/figcaption><\/figure>\n\n\n\n<p>La crise du coronavirus a contribu\u00e9 \u00e0 acc\u00e9l\u00e9rer la transformation du march\u00e9 du travail fran\u00e7ais. En effet, en comparant les flux de la fin ao\u00fbt 2020 avec ceux de la fin ao\u00fbt 2019 pour tenir compte de la saisonnalit\u00e9, la propret\u00e9 et l\u2019hygi\u00e8ne et les services \u00e0 la personne (garde d\u2019enfants, soins personnels et \u00e0 domicile en particulier) sont les secteurs qui affichent la plus forte progression dans la part des nouvelles offres d\u2019emploi. L\u2019enseignement et la formation affiche un recul tr\u00e8s important (3,2 points de pourcentage sur l\u2019ann\u00e9e, et 1,2 point depuis le 19 avril). Les postes dans l\u2019industrie (production et fabrication et ing\u00e9nierie industrielle) reculent \u00e9galement sur l\u2019ann\u00e9e. Les fonctions de comptabilit\u00e9 et management r\u00e9sistent en revanche plut\u00f4t bien sur l\u2019ann\u00e9e, alors qu\u2019elles avaient fortement recul\u00e9 pendant le confinement. Ce n\u2019est pas le cas pour les services administratifs ou les ressources humaines, qui voient leur importance s\u2019effriter.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/rXr6vnigoaARtHF-7G-j3TnsVWsKFMEEr49gqXTfoKF4tcZFRPh6RioN6GEthUA3Tsd63i7JV-zvK7mRBRoJRX3PBDCwWeoUtlsooBkfHWSK2eu4AsVHgtFP9OLNJmXbotMhboGE\" alt=\"\u00c9volution sur un an du march\u00e9 du travail\" \/><figcaption>Le tableau en deux parties illustre la variation de la part des nouvelles offres d&#8217;emploi par rapport \u00e0 2019. La premi\u00e8re partie du tableau liste les m\u00e9tiers dont la part a augment\u00e9 et leur variation en points de pourcentage. De haut en bas : Propret\u00e9 et hygi\u00e8ne 1,7 ; Garde d&rsquo;enfants 1,7 ; Soins personnels et \u00e0 domicile 0,7 ; Construction 0,3 ; Maintenance et r\u00e9paration 0,3 ; M\u00e9decine 0,3 ; Comptabilit\u00e9 0,1 ; Immobilier 0,1 ; S\u00e9curit\u00e9 et protection publique 0,1 ; Services de proximit\u00e9 0,1. La deuxi\u00e8me partie du tableau liste les m\u00e9tiers dont la part a diminu\u00e9 et leur variation en points de pourcentage. De haut en bas : Enseignement et formation -3,2 ; Production et fabrication -0,6 ; Services administratifs -0,5 ; Vente et prospection commerciale -0,4 ; Restauration -0,4 ; Service clients -0,4 ; Ing\u00e9nierie industrielle -0,3 ; Ressources humaines -0,2 ; Architecture -0,2 ; Transport et logistique -0,1. Une note indique que les donn\u00e9es sont au 28 ao\u00fbt. La source des donn\u00e9es est Indeed.<\/figcaption><\/figure>\n\n\n\n<p>Pour l\u2019instant, la propret\u00e9 et l\u2019hygi\u00e8ne et les services \u00e0 la personne apparaissent donc comme les grands gagnants de la crise, alors que l\u2019enseignement, la formation et l\u2019industrie voient leur part dans les offres reculer. Gageons que pour ces derniers secteurs, le plan de relance de l\u2019\u00e9conomie parviendra \u00e0 inverser la tendance.<\/p>\n\n\n\n<p><strong>M\u00e9thodologie<\/strong><\/p>\n\n\n\n<p>Pour mesurer l&rsquo;\u00e9volution des nouvelles offres d&#8217;emploi, d\u00e9finies comme des annonces publi\u00e9es sur le site fran\u00e7ais d&rsquo;Indeed depuis sept jours ou moins, nous avons calcul\u00e9 la moyenne mobile sur sept jours du nombre d&rsquo;offres d&#8217;emploi sur Indeed.fr. Nous avons compar\u00e9 cette moyenne mobile sur trois p\u00e9riodes : le 28 ao\u00fbt 2019, le 19 avril 2020 et le 28 ao\u00fbt 2020.<\/p>\n\n\n\n<p>Le point bas du cycle de recrutement, le 19 avril 2020, refl\u00e8te \u00e0 la fois le plus faible volume de nouvelles offres d&#8217;emploi et l&rsquo;\u00e9cart le plus important entre la tendance de cette ann\u00e9e et celle de l&rsquo;ann\u00e9e derni\u00e8re.&nbsp;<\/p>\n\n\n\n<p>L&rsquo;analyse sectorielle est d\u00e9termin\u00e9e en calculant la part des nouvelles offres d&#8217;emploi pour chaque secteur et sur chaque p\u00e9riode.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La comparaison des flux de nouvelles offres avant, pendant et apr\u00e8s la crise permet de mettre en \u00e9vidence la progression des m\u00e9tiers de la propret\u00e9, de l\u2019hygi\u00e8ne et les services \u00e0 la personne, alors que l\u2019industrie d\u00e9cline.<\/p>\n","protected":false},"author":37,"featured_media":11457,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"recruiter-hub-blocks.php","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"post_mwm_category":[222],"post_topic":[],"post_content_type":[],"post_duration":[],"post_actions":[],"post_franchise":[],"post_mwm_author":[189],"class_list":["post-11447","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","post_mwm_category-coronavirus","post_mwm_author-ajudes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le march\u00e9 du travail se transforme sous l\u2019effet de la crise du coronavirus - Indeed Hiring Lab France<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hiringlab.org\/fr\/blog\/2020\/09\/04\/marche-du-travail-se-transforme-coronavirus\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le march\u00e9 du travail se transforme sous l\u2019effet de la crise du coronavirus - Indeed Hiring Lab France\" \/>\n<meta property=\"og:description\" content=\"La comparaison des flux de nouvelles offres avant, pendant et apr\u00e8s la crise permet de mettre en \u00e9vidence la progression des m\u00e9tiers de la propret\u00e9, de l\u2019hygi\u00e8ne et les services \u00e0 la personne, alors que l\u2019industrie d\u00e9cline.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hiringlab.org\/fr\/blog\/2020\/09\/04\/marche-du-travail-se-transforme-coronavirus\/\" \/>\n<meta property=\"og:site_name\" content=\"Indeed Hiring Lab France\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-04T14:01:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hiringlab.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/09\/How-to-Post-a-Job-on-Indeed.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alexandre Judes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2020\\\/09\\\/04\\\/marche-du-travail-se-transforme-coronavirus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2020\\\/09\\\/04\\\/marche-du-travail-se-transforme-coronavirus\\\/\"},\"author\":{\"name\":\"Alexandre Judes\",\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/#\\\/schema\\\/person\\\/35a85469aa9821aef8af2a600eb69c82\"},\"headline\":\"Le march\u00e9 du travail se transforme sous l\u2019effet de la crise du coronavirus\",\"datePublished\":\"2020-09-04T14:01:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2020\\\/09\\\/04\\\/marche-du-travail-se-transforme-coronavirus\\\/\"},\"wordCount\":1098,\"image\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2020\\\/09\\\/04\\\/marche-du-travail-se-transforme-coronavirus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d341ezm4iqaae0.cloudfront.net\\\/hiringlaborg\\\/sites\\\/4\\\/2020\\\/09\\\/02182342\\\/How-to-Post-a-Job-on-Indeed.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2020\\\/09\\\/04\\\/marche-du-travail-se-transforme-coronavirus\\\/\",\"url\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2020\\\/09\\\/04\\\/marche-du-travail-se-transforme-coronavirus\\\/\",\"name\":\"Le march\u00e9 du travail se transforme sous l\u2019effet de la crise du coronavirus - Indeed Hiring Lab France\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2020\\\/09\\\/04\\\/marche-du-travail-se-transforme-coronavirus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2020\\\/09\\\/04\\\/marche-du-travail-se-transforme-coronavirus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d341ezm4iqaae0.cloudfront.net\\\/hiringlaborg\\\/sites\\\/4\\\/2020\\\/09\\\/02182342\\\/How-to-Post-a-Job-on-Indeed.jpg\",\"datePublished\":\"2020-09-04T14:01:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/#\\\/schema\\\/person\\\/35a85469aa9821aef8af2a600eb69c82\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2020\\\/09\\\/04\\\/marche-du-travail-se-transforme-coronavirus\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2020\\\/09\\\/04\\\/marche-du-travail-se-transforme-coronavirus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2020\\\/09\\\/04\\\/marche-du-travail-se-transforme-coronavirus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/d341ezm4iqaae0.cloudfront.net\\\/hiringlaborg\\\/sites\\\/4\\\/2020\\\/09\\\/02182342\\\/How-to-Post-a-Job-on-Indeed.jpg\",\"contentUrl\":\"https:\\\/\\\/d341ezm4iqaae0.cloudfront.net\\\/hiringlaborg\\\/sites\\\/4\\\/2020\\\/09\\\/02182342\\\/How-to-Post-a-Job-on-Indeed.jpg\",\"width\":1500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2020\\\/09\\\/04\\\/marche-du-travail-se-transforme-coronavirus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le march\u00e9 du travail se transforme sous l\u2019effet de la crise du coronavirus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/\",\"name\":\"Indeed Hiring Lab France\",\"description\":\"Just another Wordpress Admins Site Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/#\\\/schema\\\/person\\\/35a85469aa9821aef8af2a600eb69c82\",\"name\":\"Alexandre Judes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4ea58a3c345a594b916e5eab9862bcc2ae6f5489e8b11392ff7df04ef9174c2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4ea58a3c345a594b916e5eab9862bcc2ae6f5489e8b11392ff7df04ef9174c2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4ea58a3c345a594b916e5eab9862bcc2ae6f5489e8b11392ff7df04ef9174c2?s=96&d=mm&r=g\",\"caption\":\"Alexandre Judes\"},\"url\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/author\\\/ajudes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le march\u00e9 du travail se transforme sous l\u2019effet de la crise du coronavirus - Indeed Hiring Lab France","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hiringlab.org\/fr\/blog\/2020\/09\/04\/marche-du-travail-se-transforme-coronavirus\/","og_locale":"fr_FR","og_type":"article","og_title":"Le march\u00e9 du travail se transforme sous l\u2019effet de la crise du coronavirus - Indeed Hiring Lab France","og_description":"La comparaison des flux de nouvelles offres avant, pendant et apr\u00e8s la crise permet de mettre en \u00e9vidence la progression des m\u00e9tiers de la propret\u00e9, de l\u2019hygi\u00e8ne et les services \u00e0 la personne, alors que l\u2019industrie d\u00e9cline.","og_url":"https:\/\/www.hiringlab.org\/fr\/blog\/2020\/09\/04\/marche-du-travail-se-transforme-coronavirus\/","og_site_name":"Indeed Hiring Lab France","article_published_time":"2020-09-04T14:01:44+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/www.hiringlab.org\/fr\/wp-content\/uploads\/sites\/4\/2020\/09\/How-to-Post-a-Job-on-Indeed.jpg","type":"image\/jpeg"}],"author":"Alexandre Judes","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2020\/09\/04\/marche-du-travail-se-transforme-coronavirus\/#article","isPartOf":{"@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2020\/09\/04\/marche-du-travail-se-transforme-coronavirus\/"},"author":{"name":"Alexandre Judes","@id":"https:\/\/www.hiringlab.org\/fr\/#\/schema\/person\/35a85469aa9821aef8af2a600eb69c82"},"headline":"Le march\u00e9 du travail se transforme sous l\u2019effet de la crise du coronavirus","datePublished":"2020-09-04T14:01:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2020\/09\/04\/marche-du-travail-se-transforme-coronavirus\/"},"wordCount":1098,"image":{"@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2020\/09\/04\/marche-du-travail-se-transforme-coronavirus\/#primaryimage"},"thumbnailUrl":"https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2020\/09\/02182342\/How-to-Post-a-Job-on-Indeed.jpg","articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2020\/09\/04\/marche-du-travail-se-transforme-coronavirus\/","url":"https:\/\/www.hiringlab.org\/fr\/blog\/2020\/09\/04\/marche-du-travail-se-transforme-coronavirus\/","name":"Le march\u00e9 du travail se transforme sous l\u2019effet de la crise du coronavirus - Indeed Hiring Lab France","isPartOf":{"@id":"https:\/\/www.hiringlab.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2020\/09\/04\/marche-du-travail-se-transforme-coronavirus\/#primaryimage"},"image":{"@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2020\/09\/04\/marche-du-travail-se-transforme-coronavirus\/#primaryimage"},"thumbnailUrl":"https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2020\/09\/02182342\/How-to-Post-a-Job-on-Indeed.jpg","datePublished":"2020-09-04T14:01:44+00:00","author":{"@id":"https:\/\/www.hiringlab.org\/fr\/#\/schema\/person\/35a85469aa9821aef8af2a600eb69c82"},"breadcrumb":{"@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2020\/09\/04\/marche-du-travail-se-transforme-coronavirus\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hiringlab.org\/fr\/blog\/2020\/09\/04\/marche-du-travail-se-transforme-coronavirus\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2020\/09\/04\/marche-du-travail-se-transforme-coronavirus\/#primaryimage","url":"https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2020\/09\/02182342\/How-to-Post-a-Job-on-Indeed.jpg","contentUrl":"https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2020\/09\/02182342\/How-to-Post-a-Job-on-Indeed.jpg","width":1500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2020\/09\/04\/marche-du-travail-se-transforme-coronavirus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hiringlab.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Le march\u00e9 du travail se transforme sous l\u2019effet de la crise du coronavirus"}]},{"@type":"WebSite","@id":"https:\/\/www.hiringlab.org\/fr\/#website","url":"https:\/\/www.hiringlab.org\/fr\/","name":"Indeed Hiring Lab France","description":"Just another Wordpress Admins Site Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hiringlab.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.hiringlab.org\/fr\/#\/schema\/person\/35a85469aa9821aef8af2a600eb69c82","name":"Alexandre Judes","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d4ea58a3c345a594b916e5eab9862bcc2ae6f5489e8b11392ff7df04ef9174c2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d4ea58a3c345a594b916e5eab9862bcc2ae6f5489e8b11392ff7df04ef9174c2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d4ea58a3c345a594b916e5eab9862bcc2ae6f5489e8b11392ff7df04ef9174c2?s=96&d=mm&r=g","caption":"Alexandre Judes"},"url":"https:\/\/www.hiringlab.org\/fr\/blog\/author\/ajudes\/"}]}},"_links":{"self":[{"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/posts\/11447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/comments?post=11447"}],"version-history":[{"count":0,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/posts\/11447\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/media\/11457"}],"wp:attachment":[{"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/media?parent=11447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/categories?post=11447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/tags?post=11447"},{"taxonomy":"post_mwm_category","embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/post_mwm_category?post=11447"},{"taxonomy":"post_topic","embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/post_topic?post=11447"},{"taxonomy":"post_content_type","embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/post_content_type?post=11447"},{"taxonomy":"post_duration","embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/post_duration?post=11447"},{"taxonomy":"post_actions","embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/post_actions?post=11447"},{"taxonomy":"post_franchise","embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/post_franchise?post=11447"},{"taxonomy":"post_mwm_author","embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/post_mwm_author?post=11447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}