{"id":11092,"date":"2019-09-23T00:01:00","date_gmt":"2019-09-22T22:01:00","guid":{"rendered":"https:\/\/www.hiringlab.org\/fr\/?p=11092"},"modified":"2019-09-23T00:01:00","modified_gmt":"2019-09-22T22:01:00","slug":"le-travail-independant","status":"publish","type":"post","link":"https:\/\/www.hiringlab.org\/fr\/blog\/2019\/09\/23\/le-travail-independant\/","title":{"rendered":"Le travail ind\u00e9pendant attire de plus en plus les chercheurs d\u2019emploi"},"content":{"rendered":"\n<p>Le nombre de recherches de la part des candidats est en forte augmentation sur les quatre derni\u00e8res ann\u00e9es mais le nombre d\u2019offres d\u2019emploi augmente plus mod\u00e9r\u00e9ment.<\/p>\n\n\n\n<p>Alors que la transformation num\u00e9rique affecte de plus en plus de secteurs, les responsables publics comme les DRH s\u2019interrogent sur les mutations du travail et la p\u00e9rennit\u00e9 du salariat. Si les chiffres de l\u2019INSEE semblent confirmer l\u2019int\u00e9r\u00eat de la plupart des actifs pour le salariat (87 % des personnes emploi sont salari\u00e9es), et plus particuli\u00e8rement la forme la plus prot\u00e9g\u00e9e de celui-ci (87 % des salari\u00e9s sont en CDI \u2014 contrat \u00e0 dur\u00e9e ind\u00e9termin\u00e9e), les recherches sur Indeed.fr contenant le mot cl\u00e9 \u00ab freelance \u00bb connaissent une augmentation de 131 % par rapport \u00e0 2015. Les offres d\u2019emploi de \u00ab freelance \u00bb progressent plus lentement, \u00e0 34 % par rapport \u00e0 2015.<br><\/p>\n\n\n\n<p>Alors qu\u2019en 2015, on observait \u00e0 peu pr\u00e8s 1 recherche contenant le mot \u00ab freelance \u00bb pour une offre, ce ratio a entre temps doubl\u00e9. N\u00e9anmoins, seules 11 recherches sur 10 000 contiennent le mot \u00ab freelance \u00bb, alors que du c\u00f4t\u00e9 des offres, les postes ouverts en \u00ab freelance \u00bb repr\u00e9sentent 60 offres pour 10 000 annonces post\u00e9es. Si l\u2019engouement pour le \u00ab freelancing \u00bb ne peut pas \u00eatre ni\u00e9, il peut donc encore progresser parmi les chercheurs d\u2019emploi pour arriver \u00e0 un niveau qui permettrait aux recruteurs d\u2019avoir plus de choix.<br><\/p>\n\n\n\n<p><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le nombre de recherches de la part des candidats est en forte augmentation sur les quatre derni\u00e8res ann\u00e9es mais le nombre d\u2019offres d\u2019emploi augmente plus mod\u00e9r\u00e9ment. Alors que la transformation num\u00e9rique affecte de plus en plus de secteurs, les responsables publics comme les DRH s\u2019interrogent sur les mutations du travail et la p\u00e9rennit\u00e9 du salariat. [&hellip;]<\/p>\n","protected":false},"author":37,"featured_media":11094,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"recruiter-hub-blocks.php","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"post_mwm_category":[223],"post_topic":[],"post_content_type":[],"post_duration":[],"post_actions":[],"post_franchise":[],"post_mwm_author":[189],"class_list":["post-11092","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","post_mwm_category-uncategorized","post_mwm_author-ajudes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le travail ind\u00e9pendant attire de plus en plus les chercheurs d\u2019emploi - Indeed Hiring Lab France<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hiringlab.org\/fr\/blog\/2019\/09\/23\/le-travail-independant\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le travail ind\u00e9pendant attire de plus en plus les chercheurs d\u2019emploi - Indeed Hiring Lab France\" \/>\n<meta property=\"og:description\" content=\"Le nombre de recherches de la part des candidats est en forte augmentation sur les quatre derni\u00e8res ann\u00e9es mais le nombre d\u2019offres d\u2019emploi augmente plus mod\u00e9r\u00e9ment. Alors que la transformation num\u00e9rique affecte de plus en plus de secteurs, les responsables publics comme les DRH s\u2019interrogent sur les mutations du travail et la p\u00e9rennit\u00e9 du salariat. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hiringlab.org\/fr\/blog\/2019\/09\/23\/le-travail-independant\/\" \/>\n<meta property=\"og:site_name\" content=\"Indeed Hiring Lab France\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-22T22:01:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hiringlab.org\/fr\/wp-content\/uploads\/sites\/4\/2019\/09\/freelance.png\" \/>\n\t<meta property=\"og:image:width\" content=\"939\" \/>\n\t<meta property=\"og:image:height\" content=\"556\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Alexandre Judes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2019\\\/09\\\/23\\\/le-travail-independant\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2019\\\/09\\\/23\\\/le-travail-independant\\\/\"},\"author\":{\"name\":\"Alexandre Judes\",\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/#\\\/schema\\\/person\\\/35a85469aa9821aef8af2a600eb69c82\"},\"headline\":\"Le travail ind\u00e9pendant attire de plus en plus les chercheurs d\u2019emploi\",\"datePublished\":\"2019-09-22T22:01:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2019\\\/09\\\/23\\\/le-travail-independant\\\/\"},\"wordCount\":239,\"image\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2019\\\/09\\\/23\\\/le-travail-independant\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d341ezm4iqaae0.cloudfront.net\\\/hiringlaborg\\\/sites\\\/4\\\/2019\\\/09\\\/02182431\\\/freelance.png\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2019\\\/09\\\/23\\\/le-travail-independant\\\/\",\"url\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2019\\\/09\\\/23\\\/le-travail-independant\\\/\",\"name\":\"Le travail ind\u00e9pendant attire de plus en plus les chercheurs d\u2019emploi - Indeed Hiring Lab France\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2019\\\/09\\\/23\\\/le-travail-independant\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2019\\\/09\\\/23\\\/le-travail-independant\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d341ezm4iqaae0.cloudfront.net\\\/hiringlaborg\\\/sites\\\/4\\\/2019\\\/09\\\/02182431\\\/freelance.png\",\"datePublished\":\"2019-09-22T22:01:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/#\\\/schema\\\/person\\\/35a85469aa9821aef8af2a600eb69c82\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2019\\\/09\\\/23\\\/le-travail-independant\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2019\\\/09\\\/23\\\/le-travail-independant\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2019\\\/09\\\/23\\\/le-travail-independant\\\/#primaryimage\",\"url\":\"https:\\\/\\\/d341ezm4iqaae0.cloudfront.net\\\/hiringlaborg\\\/sites\\\/4\\\/2019\\\/09\\\/02182431\\\/freelance.png\",\"contentUrl\":\"https:\\\/\\\/d341ezm4iqaae0.cloudfront.net\\\/hiringlaborg\\\/sites\\\/4\\\/2019\\\/09\\\/02182431\\\/freelance.png\",\"width\":939,\"height\":556,\"caption\":\"Le graphique en courbes indique le ratio entre le nombre de recherches et le nombre d\u2019offres contenant le mot freelance, de 0 \u00e0 3,5 sur son axe vertical. L\u2019axe horizontal indique les dates, d\u2019ao\u00fbt 2015 \u00e0 ao\u00fbt 2019. La source des donn\u00e9es est Indeed.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/2019\\\/09\\\/23\\\/le-travail-independant\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le travail ind\u00e9pendant attire de plus en plus les chercheurs d\u2019emploi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/\",\"name\":\"Indeed Hiring Lab France\",\"description\":\"Just another Wordpress Admins Site Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/#\\\/schema\\\/person\\\/35a85469aa9821aef8af2a600eb69c82\",\"name\":\"Alexandre Judes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4ea58a3c345a594b916e5eab9862bcc2ae6f5489e8b11392ff7df04ef9174c2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4ea58a3c345a594b916e5eab9862bcc2ae6f5489e8b11392ff7df04ef9174c2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4ea58a3c345a594b916e5eab9862bcc2ae6f5489e8b11392ff7df04ef9174c2?s=96&d=mm&r=g\",\"caption\":\"Alexandre Judes\"},\"url\":\"https:\\\/\\\/www.hiringlab.org\\\/fr\\\/blog\\\/author\\\/ajudes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le travail ind\u00e9pendant attire de plus en plus les chercheurs d\u2019emploi - Indeed Hiring Lab France","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hiringlab.org\/fr\/blog\/2019\/09\/23\/le-travail-independant\/","og_locale":"fr_FR","og_type":"article","og_title":"Le travail ind\u00e9pendant attire de plus en plus les chercheurs d\u2019emploi - Indeed Hiring Lab France","og_description":"Le nombre de recherches de la part des candidats est en forte augmentation sur les quatre derni\u00e8res ann\u00e9es mais le nombre d\u2019offres d\u2019emploi augmente plus mod\u00e9r\u00e9ment. Alors que la transformation num\u00e9rique affecte de plus en plus de secteurs, les responsables publics comme les DRH s\u2019interrogent sur les mutations du travail et la p\u00e9rennit\u00e9 du salariat. [&hellip;]","og_url":"https:\/\/www.hiringlab.org\/fr\/blog\/2019\/09\/23\/le-travail-independant\/","og_site_name":"Indeed Hiring Lab France","article_published_time":"2019-09-22T22:01:00+00:00","og_image":[{"width":939,"height":556,"url":"https:\/\/www.hiringlab.org\/fr\/wp-content\/uploads\/sites\/4\/2019\/09\/freelance.png","type":"image\/png"}],"author":"Alexandre Judes","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2019\/09\/23\/le-travail-independant\/#article","isPartOf":{"@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2019\/09\/23\/le-travail-independant\/"},"author":{"name":"Alexandre Judes","@id":"https:\/\/www.hiringlab.org\/fr\/#\/schema\/person\/35a85469aa9821aef8af2a600eb69c82"},"headline":"Le travail ind\u00e9pendant attire de plus en plus les chercheurs d\u2019emploi","datePublished":"2019-09-22T22:01:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2019\/09\/23\/le-travail-independant\/"},"wordCount":239,"image":{"@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2019\/09\/23\/le-travail-independant\/#primaryimage"},"thumbnailUrl":"https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2019\/09\/02182431\/freelance.png","articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2019\/09\/23\/le-travail-independant\/","url":"https:\/\/www.hiringlab.org\/fr\/blog\/2019\/09\/23\/le-travail-independant\/","name":"Le travail ind\u00e9pendant attire de plus en plus les chercheurs d\u2019emploi - Indeed Hiring Lab France","isPartOf":{"@id":"https:\/\/www.hiringlab.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2019\/09\/23\/le-travail-independant\/#primaryimage"},"image":{"@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2019\/09\/23\/le-travail-independant\/#primaryimage"},"thumbnailUrl":"https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2019\/09\/02182431\/freelance.png","datePublished":"2019-09-22T22:01:00+00:00","author":{"@id":"https:\/\/www.hiringlab.org\/fr\/#\/schema\/person\/35a85469aa9821aef8af2a600eb69c82"},"breadcrumb":{"@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2019\/09\/23\/le-travail-independant\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hiringlab.org\/fr\/blog\/2019\/09\/23\/le-travail-independant\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2019\/09\/23\/le-travail-independant\/#primaryimage","url":"https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2019\/09\/02182431\/freelance.png","contentUrl":"https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/4\/2019\/09\/02182431\/freelance.png","width":939,"height":556,"caption":"Le graphique en courbes indique le ratio entre le nombre de recherches et le nombre d\u2019offres contenant le mot freelance, de 0 \u00e0 3,5 sur son axe vertical. L\u2019axe horizontal indique les dates, d\u2019ao\u00fbt 2015 \u00e0 ao\u00fbt 2019. La source des donn\u00e9es est Indeed."},{"@type":"BreadcrumbList","@id":"https:\/\/www.hiringlab.org\/fr\/blog\/2019\/09\/23\/le-travail-independant\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hiringlab.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Le travail ind\u00e9pendant attire de plus en plus les chercheurs d\u2019emploi"}]},{"@type":"WebSite","@id":"https:\/\/www.hiringlab.org\/fr\/#website","url":"https:\/\/www.hiringlab.org\/fr\/","name":"Indeed Hiring Lab France","description":"Just another Wordpress Admins Site Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hiringlab.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.hiringlab.org\/fr\/#\/schema\/person\/35a85469aa9821aef8af2a600eb69c82","name":"Alexandre Judes","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d4ea58a3c345a594b916e5eab9862bcc2ae6f5489e8b11392ff7df04ef9174c2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d4ea58a3c345a594b916e5eab9862bcc2ae6f5489e8b11392ff7df04ef9174c2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d4ea58a3c345a594b916e5eab9862bcc2ae6f5489e8b11392ff7df04ef9174c2?s=96&d=mm&r=g","caption":"Alexandre Judes"},"url":"https:\/\/www.hiringlab.org\/fr\/blog\/author\/ajudes\/"}]}},"_links":{"self":[{"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/posts\/11092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/comments?post=11092"}],"version-history":[{"count":0,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/posts\/11092\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/media\/11094"}],"wp:attachment":[{"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/media?parent=11092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/categories?post=11092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/tags?post=11092"},{"taxonomy":"post_mwm_category","embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/post_mwm_category?post=11092"},{"taxonomy":"post_topic","embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/post_topic?post=11092"},{"taxonomy":"post_content_type","embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/post_content_type?post=11092"},{"taxonomy":"post_duration","embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/post_duration?post=11092"},{"taxonomy":"post_actions","embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/post_actions?post=11092"},{"taxonomy":"post_franchise","embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/post_franchise?post=11092"},{"taxonomy":"post_mwm_author","embeddable":true,"href":"https:\/\/www.hiringlab.org\/fr\/wp-json\/wp\/v2\/post_mwm_author?post=11092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}