{"id":12578,"date":"2025-04-14T23:38:52","date_gmt":"2025-04-14T21:38:52","guid":{"rendered":"https:\/\/www.hiringlab.org\/de\/?p=12578"},"modified":"2025-05-22T17:21:49","modified_gmt":"2025-05-22T15:21:49","slug":"arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich","status":"publish","type":"post","link":"https:\/\/www.hiringlab.org\/de\/blog\/2025\/04\/14\/arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich\/","title":{"rendered":"Arbeitsmarkt Update Q1 2025: Abw\u00e4rtstrend auf dem Stellenmarkt beschleunigt sich"},"content":{"rendered":"\n<p>Die wichtigsten Ergebnisse im \u00dcberblick:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Die Zahl der ausgeschriebenen Stellen auf Indeed in Deutschland ist im ersten Quartal 2025 um 7,2 Prozent zur\u00fcckgegangen. Damit hat sich der Abw\u00e4rtstrend der vergangenen Quartale noch einmal beschleunigt.<\/li>\n\n\n\n<li>R\u00fcckg\u00e4nge sind derzeit in allen Berufsgruppen zu verzeichnen. Vergleichsweise stabil sind Jobs in sozialen Bereichen wie Sozialarbeit &amp; Sozialdienst, Therapie und Pflege.<\/li>\n\n\n\n<li>Das Personalwesen als Fr\u00fchindikator f\u00fcr den Gesamtmarkt zeigt noch keine Anzeichen f\u00fcr eine Trendumkehr.<\/li>\n\n\n\n<li>Im Vergleich zu anderen europ\u00e4ischen L\u00e4ndern sowie den USA und Kanada entwickelt sich der deutsche Stellenmarkt seit Jahresbeginn besonders schwach.<\/li>\n\n\n\n<li>Suchanfragen auf Indeed nach Begriffen aus dem Bereich der R\u00fcstungsindustrie sind im Zuge der Debatte um Verteidigungsausgaben stark gestiegen.<\/li>\n<\/ul>\n\n\n\n<p><em>Unser quartalsweise erscheinendes Arbeitsmarkt Update betrachtet wichtige Trends auf dem Arbeitsmarkt unter Verwendung von Indeed-Daten und erg\u00e4nzt damit Daten der amtlichen Statistik. Die hier verwendeten Indeed Daten werden regelm\u00e4\u00dfig aktualisiert und k\u00f6nnen in unserem <\/em><a href=\"https:\/\/data.indeed.com\/\"><em>Indeed Datenportal<\/em><\/a><em> frei abgerufen werden.&nbsp;<\/em><\/p>\n\n\n\n<p>Konjunkturelle Schw\u00e4che, geopolitische Spannungen und der zuletzt eskalierende Handelskonflikt mit den USA spiegeln sich im aktuellen Zustand des deutschen Arbeitsmarkts wider. Der Indeed Arbeitsmarkt Index zeigt f\u00fcr das erste Quartal 2025 einen beschleunigten R\u00fcckgang der Stellenausschreibungen \u2013 mit erstmals sinkenden Zahlen in allen Berufsgruppen. Neue Impulse k\u00f6nnten aus staatlichen Investitionen in Verteidigung und Infrastruktur kommen. Bis sich diese am Arbeitsmarkt zeigen, wird es vermutlich noch Monate dauern. An Besch\u00e4ftigungsm\u00f6glichkeiten in der R\u00fcstungsindustrie zeigen sich Jobsuchende aber schon jetzt interessiert.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Abw\u00e4rtstrend auf dem Stellenmarkt beschleunigt sich im ersten Quartal 2025<\/strong><\/h2>\n\n\n\n<p>Die Nachfrage nach Arbeitskr\u00e4ften ist im ersten Quartal 2025 weiter zur\u00fcckgegangen. Seit Jahresbeginn ist der Indeed Arbeitsmarkt Index, der die Zahl der Stellenausschreibungen auf Indeed misst, um 7,2 Prozent gesunken. Hiermit hat sich der Abw\u00e4rtstrend in der Arbeitskr\u00e4ftenachfrage zuletzt beschleunigt: Im vierten Quartal 2024 war der Indeed Arbeitsmarkt Index um -0,9 Prozent zur\u00fcckgegangen. Im Vergleich zum Vorjahreszeitpunkt Ende M\u00e4rz 2024 waren 17,5 Prozent weniger Stellen ausgeschrieben, seit dem H\u00f6chststand im Mai 2022 mehr als 30 Prozent weniger.<\/p>\n\n\n\n<figure class=\"wp-block-image is-style-default\"><img decoding=\"async\" src=\"https:\/\/lh7-rt.googleusercontent.com\/docsz\/AD_4nXelMjzFkJijO3MIRWeZT2wJ61eOpkQszlFaD_ZbiiMV2SnEg7RVYRgrVp4hJI3AKLvGEPqXFSACvi995QkGoeII3obosvSRR4SeGLFsiHfU6BVWJfOZ0Wdff_3yI5U0NIWX6xPNCQ?key=Sxus9qQuh7jFxPHxrG8gQepG\" alt=\"Das Liniendiagramm mit dem Titel \u201cR\u00fcckgang der Arbeitskr\u00e4ftenachfrage setzt sich im ersten Quartal 2025 fort\u201d zeigt die Entwicklung des Indeed Arbeitsmarkt Index bis zum 28. M\u00e4rz 2025. Die Zahl der ausgeschriebenen Stellen ist seit 2022 r\u00fcckl\u00e4ufig. Im ersten Quartal 2025 hat sich der R\u00fcckgang im Vergleich zu den Vorquartalen sogar noch einmal beschleunigt.\" \/><figcaption class=\"wp-element-caption\"><em>Das Liniendiagramm mit dem Titel \u201cR\u00fcckgang der Arbeitskr\u00e4ftenachfrage setzt sich im ersten Quartal 2025 fort\u201d zeigt die Entwicklung des Indeed Arbeitsmarkt Index bis zum 28. M\u00e4rz 2025. Die Zahl der ausgeschriebenen Stellen ist seit 2022 r\u00fcckl\u00e4ufig. Im ersten Quartal 2025 hat sich der R\u00fcckgang im Vergleich zu den Vorquartalen sogar noch einmal beschleunigt.<\/em><\/figcaption><\/figure>\n\n\n\n<p>Der R\u00fcckgang der Arbeitskr\u00e4ftenachfrage spiegelt die anhaltend schwache Konjunktur wider. Die deutsche Wirtschaft <a href=\"https:\/\/www.tagesschau.de\/wirtschaft\/konjunktur\/wirtschaft-bruttoinlandsprodukt-100.html\">schrumpfte im Jahr 2024 um 0,2 Prozent<\/a>. F\u00fcr 2025 wird mit <a href=\"https:\/\/www.diw.de\/de\/diw_01.c.941005.de\/diw-konjunkturprognose__deutschland_kommt_in_trippelschritten_aus_der_stagnation.html\">Stagnation<\/a> oder<a href=\"https:\/\/www.ifo.de\/fakten\/2025-03-17\/ifo-konjunkturprognose-fruehjahr-2025-deutsche-wirtschaft-steckt-fest\"> minimalem Wachstum<\/a> gerechnet. Vor dem Hintergrund der zuletzt eskalierenden globalen Zollkonflikte droht jedoch eine erneute Rezession.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>R\u00fcckgang betrifft alle Berufsgruppen<\/strong><\/h2>\n\n\n\n<p>Die Zahl der ausgeschriebenen Stellen ist im ersten Quartal 2025 in allen Berufsgruppen zur\u00fcckgegangen \u2013 ein Novum im Vergleich zu den Vorquartalen, in denen zumindest einige Branchen noch Zuw\u00e4chse verzeichneten. Am geringsten war der R\u00fcckgang im Bereich Private &amp; \u00f6ffentliche Sicherheit mit -0,7 Prozent. Vergleichsweise stabil blieb die Nachfrage auch in sozialen Berufen, darunter Sozialdienst &amp; Sozialarbeit (-1,3 Prozent), Therapie (-3,2 Prozent), Bildung &amp; Erziehung (-4,5 Prozent) oder Gesundheits-, Kranken- &amp; Altenpflege (-4,6 Prozent). Diese Gruppen umfassen viele systemrelevante Berufe, die tendenziell weniger stark von konjunkturellen Schwankungen betroffen sind. Besonders schlecht entwickelten sich im ersten Quartal 2025 das Transportwesen (-16,3 Prozent), des Weiteren&nbsp; Berufe in Beherbergung, Tourismus und Veranstaltungen (-14,1 Prozent) sowie Reinigungsdienste (-14,1 Prozent).<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-rt.googleusercontent.com\/docsz\/AD_4nXc_NAVVKPtUrctAVC5gv49iLkuEHg10ZWCzzezvHIEa239HF27AOFB7A5b83AAMYLdjx8FjoMrlSIWCGqBPMEC_qQfVtfS2Pxb5INT61KJdijpo0QTUWLLGuFHt6Qux04XfYxXW?key=Sxus9qQuh7jFxPHxrG8gQepG\" alt=\"Das Hanteldiagramm mit dem Titel \u201cR\u00fcckg\u00e4nge in den Stellenanzeigen im ersten Quartal 2025 in allen Berufsgruppen. Sozialer Bereich schneidet vergleichsweise gut ab.\u201d vergleicht den aktuellen Indeed Arbeitsmarkt Index verschiedener Berufsgruppen von Ende M\u00e4rz mit dem Wert am 1. Januar 2025. In allen betrachteten Berufsgruppen sind die ausgeschriebenen Stellen seit Jahresbeginn gesunken.\" \/><figcaption class=\"wp-element-caption\"><em>Das Hanteldiagramm mit dem Titel \u201cR\u00fcckg\u00e4nge in den Stellenanzeigen im ersten Quartal 2025 in allen Berufsgruppen. Sozialer Bereich schneidet vergleichsweise gut ab.\u201d vergleicht den aktuellen Indeed Arbeitsmarkt Index verschiedener Berufsgruppen von Ende M\u00e4rz mit dem Wert am 1. Januar 2025. In allen betrachteten Berufsgruppen sind die ausgeschriebenen Stellen seit Jahresbeginn gesunken.<\/em><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Internationaler Vergleich: Deutschland unter den Schlusslichtern<\/strong><\/h2>\n\n\n\n<p>Die Stellenausschreibungen auf Indeed gingen seit Jahresbeginn in vielen europ\u00e4ischen L\u00e4ndern sowie in Kanada und den USA ebenfalls zur\u00fcck. Spanien bildet die Ausnahme mit einem leichten Plus von 0,7\u202fProzent. Deutschland liegt mit -7,2 Prozent in diesem internationalen Vergleich im unteren Bereich. Nur in Gro\u00dfbritannien fiel der R\u00fcckgang mit -8,1\u202fProzent noch st\u00e4rker aus. <a href=\"https:\/\/www.hiringlab.org\/uk\/blog\/2025\/04\/01\/march-2025-labour-market-update-wage-growth-beginning-to-drift-down\/\">Hier d\u00e4mpfte zuletzt<\/a> neben einem unsicheren konjunkturellen Ausblick eine Reform der Sozialversicherungsabgaben die Nachfrage nach Arbeitskr\u00e4ften. In den \u00fcbrigen betrachteten L\u00e4ndern Italien, USA, Kanada, die Niederlande und Frankreich lagen die R\u00fcckg\u00e4nge zwischen 2,8 und 4,2 Prozent.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-rt.googleusercontent.com\/docsz\/AD_4nXe9mkMc-1_xyiqrM8ACfWL0HuOxG2hfMeY6FQKTbuHGr5qyIGavKrJst3OHccpuMMPTOoUkE7u5UOp_6qIc-7U4F0HkB_SvHGJCGsOcxnnejROTyDTY8D9rvcqyKsoHU22_i1khqQ?key=Sxus9qQuh7jFxPHxrG8gQepG\" alt=\"Das Balkendiagramm mit dem Titel \u201cStellenausschreibungen gehen in den meisten Vergleichsm\u00e4rkten zur\u00fcck, Deutschland und Gro\u00dfbritannien am st\u00e4rksten betroffen\u201d zeigt die Ver\u00e4nderung des Indeed Arbeitsmarkt Index seit Jahresbeginn f\u00fcr die L\u00e4nder Spanien, Italien, USA, Kanada, Frankreich, die Niederlande, Deutschland und Gro\u00dfbritannien. Der R\u00fcckgang war in diesem Zeitraum in Gro\u00dfbritannien am st\u00e4rksten. In Spanien stieg die Zahl der ausgeschriebenen Stellen leicht an.\" \/><figcaption class=\"wp-element-caption\"><em>Das Balkendiagramm mit dem Titel \u201cStellenausschreibungen gehen in den meisten Vergleichsm\u00e4rkten zur\u00fcck, Deutschland und Gro\u00dfbritannien am st\u00e4rksten betroffen\u201d zeigt die Ver\u00e4nderung des Indeed Arbeitsmarkt Index seit Jahresbeginn f\u00fcr die L\u00e4nder Spanien, Italien, USA, Kanada, Frankreich, die Niederlande, Deutschland und Gro\u00dfbritannien. Der R\u00fcckgang war in diesem Zeitraum in Gro\u00dfbritannien am st\u00e4rksten. In Spanien stieg die Zahl der ausgeschriebenen Stellen leicht an.<\/em><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Personalwesen als Fr\u00fchindikator: Noch keine Erholung in Sicht<\/strong><\/h2>\n\n\n\n<p>Ein Blick auf Stellenausschreibungen im Personalwesen \u2013 einem Fr\u00fchindikator f\u00fcr k\u00fcnftige Einstellungen \u2013 l\u00e4sst derzeit keine Erholung der Arbeitsnachfrage erwarten: Die Zahl der Stellenausschreibungen sank im vergangenen Jahr um 29,6 Prozent \u2013 ein st\u00e4rkerer R\u00fcckgang als im Gesamtmarkt. Seit Jahresbeginn ging die Nachfrage in dieser Berufsgruppe um 6,5 Prozent zur\u00fcck. Unternehmen scheinen also nach wie vor keine Recruitingoffensiven zu planen.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-rt.googleusercontent.com\/docsz\/AD_4nXeKu8Jxbg6fVFSHqRb-XU1L4hlxkI0cEIJeY-9xCkwasjRLkPli0NWJGSgbPKJ9BZLNpxyan37oK6cUIrOyiUlQw1-6E3RksB1HV2ItmDZsX-pSIwDaIaaCpTKoAoR5XHsoboYejg?key=Sxus9qQuh7jFxPHxrG8gQepG\" alt=\"Das Liniendiagramm mit dem Titel \u201cPersonalwesen als Fr\u00fchindikator: Noch keine Trendwende in Sicht\u201c vergleicht die Entwicklung des Indeed Arbeitsmarkt Index im Personalwesen mit dem des Gesamtmarktes. Die Stellenausschreibungen im Personalwesen sind im vergangenen Jahr st\u00e4rker gesunken als im Gesamtmarkt, und der Negativtrend hielt im ersten Quartal 2025 an.\" \/><figcaption class=\"wp-element-caption\"><em>Das Liniendiagramm mit dem Titel \u201cPersonalwesen als Fr\u00fchindikator: Noch keine Trendwende in Sicht\u201c vergleicht die Entwicklung des Indeed Arbeitsmarkt Index im Personalwesen mit dem des Gesamtmarktes. Die Stellenausschreibungen im Personalwesen sind im vergangenen Jahr st\u00e4rker gesunken als im Gesamtmarkt, und der Negativtrend hielt im ersten Quartal 2025 an.<\/em><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Debatte \u00fcber Verteidigungsausgaben weckt bei Jobsuchenden Interesse an der R\u00fcstungsindustrie<\/strong><\/h2>\n\n\n\n<p>Am 18. M\u00e4rz 2025 <a href=\"https:\/\/www.bundestag.de\/dokumente\/textarchiv\/2025\/kw11-de-sondersitzung-1056228\">verabschiedete der Bundestag<\/a> ein umfangreiches Finanzpaket: Die Schuldenbremse wurde f\u00fcr Verteidigungsausgaben gelockert und ein 500-Milliarden-Euro-Sonderverm\u00f6gen f\u00fcr Infrastrukturprojekte geschaffen. Die Ank\u00fcndigung stie\u00df <a href=\"https:\/\/www.finanzen.net\/nachricht\/aktien\/verteidigung-im-fokus-finanzpaket-schiebt-bau-und-ruestungsaktien-wie-rheinmetall-hensoldt-hochtief-bilfinger-und-heidelberg-materials-an-14292353\">an den Finanzm\u00e4rkten auf positive Reaktionen<\/a> \u2013 insbesondere bei R\u00fcstungsunternehmen wie Rheinmetall oder Hensoldt. Aktien gro\u00dfer Bauunternehmen wie Heidelberg Materials, Hochtief oder Bilfinger profitierten ebenfalls.<\/p>\n\n\n\n<p>Vom Finanzpaket werden auch am Arbeitsmarkt Impulse erwartet \u2013 etwa durch Besch\u00e4ftigungsm\u00f6glichkeiten in R\u00fcstungs- und Bauunternehmen. Besonders der Bausektor steckt derzeit in der Krise: Stellenanzeigen auf Indeed sanken im vergangenen Jahr um 12,5 Prozent. Bis sich neue Besch\u00e4ftigung konkret abzeichnet, braucht es jedoch klarere Ausgabenpl\u00e4ne \u2013 das k\u00f6nnte noch dauern.<\/p>\n\n\n\n<p>Aufseiten der Jobsuchenden scheint durchaus Interesse insbesondere an Jobs in der R\u00fcstungsindustrie zu bestehen: Seit der Bundestagswahl stiegen die t\u00e4glichen Suchanfragen auf Indeed nach relevanten Begriffen und Unternehmen der R\u00fcstungsindustrie an und erreichten kurz nach Verabschiedung des Finanzpakets ein dreimal so hohes Niveau wie Anfang Februar. Suchanfragen zur Bauindustrie blieben von der Debatte um Infrastrukturinvestitionen hingegen eher unbeeindruckt. Ende M\u00e4rz verzeichneten sie ebenfalls einen Anstieg, dieser war aber vergleichsweise klein und fand mutma\u00dflich auch im Zusammenhang mit anderen <a href=\"https:\/\/www.leadersnet.at\/news\/87887,haselsteiner-nimmt-mit-verkauf-von-strabag-aktien-132-millionen.html#:~:text=Um%20eine%20Pflichtmitteilung%20der%20Strabag,b%C3%B6rsennotierten%20Konzernen%20mitgeteilt%20werden%20m%C3%BCssen.\">Unternehmensnachrichten<\/a> zu einem der gr\u00f6\u00dften Bauunternehmen statt.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-rt.googleusercontent.com\/docsz\/AD_4nXdYb-xLEoJj3OZWC7wy0Jr2feCrgr0eAxr1QV0jkWAi6aFOkLJXb1amPnzUFXilOG5hyh7Olyw5C_oY2cnvacvckeAiFG_EuCrwKnAtH9--x5hiiVJ4JMYLPqFQ6t83uJl0ujNf6A?key=Sxus9qQuh7jFxPHxrG8gQepG\" alt=\"Das Liniendiagramm mit dem Titel \u201cInteresse Jobsuchender an R\u00fcstungsindustrie steigt im Zuge der Debatte um Verteidigungsausgaben und Reform der Schuldenbremse\u201c zeigt die Suchanfragen auf Indeed nach den Begriffen R\u00fcstungsbranche\/-industrie und den zehn gr\u00f6\u00dften R\u00fcstungsunternehmen sowie die Suchanfragen nach den Begriffen Baubranche\/-industrie und den zehn gr\u00f6\u00dften Bauunternehmen. Um die Entwicklung im Zuge der Debatte um das Finanzpaket seit der Bundestagswahl zu quantifizieren, sind die Daten zum 1. Februar 2025 indexiert.\" \/><figcaption class=\"wp-element-caption\"><em>Das Liniendiagramm mit dem Titel \u201cInteresse Jobsuchender an R\u00fcstungsindustrie steigt im Zuge der Debatte um Verteidigungsausgaben und Reform der Schuldenbremse\u201c zeigt die Suchanfragen auf Indeed nach den Begriffen R\u00fcstungsbranche\/-industrie und den zehn gr\u00f6\u00dften R\u00fcstungsunternehmen sowie die Suchanfragen nach den Begriffen Baubranche\/-industrie und den zehn gr\u00f6\u00dften Bauunternehmen. Um die Entwicklung im Zuge der Debatte um das Finanzpaket seit der Bundestagswahl zu quantifizieren, sind die Daten zum 1. Februar 2025 indexiert.<\/em><\/figcaption><\/figure>\n\n\n\n<p>Ein Grund f\u00fcr das st\u00e4rkere Interesse an der R\u00fcstungsindustrie k\u00f6nnte sein, dass diese in der \u00f6ffentlichen Debatte zunehmend als Besch\u00e4ftigungsalternative f\u00fcr Fachkr\u00e4fte aus der angeschlagenen Automobilindustrie genannt wird. Ob es nach den angek\u00fcndigten Stellenstreichungen bei gro\u00dfen Automobilkonzernen tats\u00e4chlich zu vermehrten Karrierewechseln in die R\u00fcstungsindustrie kommt, wird sich jedoch erst in den kommenden Monaten zeigen.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Methodik<\/strong><\/h2>\n\n\n\n<p>Methodische Hinweise zu den verwendeten Indeed Daten finden sich hier: <a href=\"https:\/\/www.hiringlab.org\/de\/data\/\">Indeed Arbeitsmarkt Index<\/a>, <a href=\"https:\/\/papers.ssrn.com\/sol3\/papers.cfm?abstract_id=4451751\">Indeed Gehaltstracker<\/a> und <a href=\"https:\/\/www.hiringlab.org\/2023\/06\/28\/methodology-remote-and-hybrid-jobs\/\">Indeed Homeoffice Tracker<\/a>.&nbsp;<\/p>\n\n\n\n<p>W\u00f6chentlich erscheinen <a href=\"http:\/\/data.indeed.com\">neue Daten des Indeed Arbeitsmarkt Index<\/a> und sind in unserem Datenportal frei zug\u00e4nglich. Die nahezu Echtzeitdaten des Indeed Arbeitsmarkt Index zeigen die Gesamtnachfrage nach Arbeitskr\u00e4ften auf Indeed sowie die Entwicklungen f\u00fcr einzelne Berufsgruppen. <a href=\"https:\/\/data.indeed.com\/#\/whats-new\">Im Mai 2024 hat es ein methodisches Update<\/a> gegeben, welches auch die Indeed-Daten f\u00fcr Deutschland betrifft. Um eine Vergleichbarkeit \u00fcber die Zeit zu erm\u00f6glichen, wurden alle Daten r\u00fcckwirkend neu berechnet.&nbsp;<\/p>\n\n\n\n<p>Die Zahl der Stellenausschreibungen auf Indeed.com ist kein Indikator f\u00fcr potenzielle Einnahmen oder Ertr\u00e4ge von Indeed, das einen bedeutenden Prozentsatz des HR-Technologiesegments seiner Muttergesellschaft Recruit Holdings Co., Ltd. umfasst. Dies gilt sowohl f\u00fcr bezahlte als auch unbezahlte Stellenausschreibungen. Die Zahl der Stellenausschreibungen wird nur zu Informationszwecken zur Verf\u00fcgung gestellt und ist kein Indikator f\u00fcr die Leistung von Indeed oder Recruit. Weitere Informationen \u00fcber die Umsatzerl\u00f6se des HR-Technologiesegments von Recruit finden Sie auf der Investor-Relations-Website von Recruit Holdings und in den Finanzberichten in Japan.<\/p>\n\n\n\n<p>F\u00fcr die Zahl der Suchanfragen nach Begriffen aus der R\u00fcstungs- und Bauindustrie wurden alle Suchanfragen gez\u00e4hlt, die die Begriffe R\u00fcstungsindustrie\/-branche sowie die <a href=\"https:\/\/www.produktion.de\/schwerpunkte\/ruestungsindustrie\/top-10-die-groessten-ruestungsunternehmen-deutschlands-190614-194.html\">zehn gr\u00f6\u00dften R\u00fcstungsunternehmen nach deren Umsatz<\/a> und die Begriffe Bauindustrie\/-branche sowie die <a href=\"https:\/\/www.bauindustrie.de\/zahlen-fakten\/branchenstruktur\/die-50-groessten-bauunternehmen\">zehn gr\u00f6\u00dften Bauunternehmen nach deren Gesamtleistung<\/a> beinhalteten. Es wurde ein rollierender Durchschnitt der t\u00e4glichen Anzahl der Suchanfragen berechnet, um f\u00fcr w\u00f6chentliche Schwankungen zu kontrollieren.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Zahl der ausgeschriebenen Stellen auf Indeed in Deutschland ist im ersten Quartal 2025 um 7,2 Prozent zur\u00fcckgegangen. Damit hat sich der Abw\u00e4rtstrend der vergangenen Quartale noch einmal beschleunigt.<\/p>\n","protected":false},"author":103,"featured_media":12570,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"recruiter-hub-blocks.php","format":"standard","meta":{"_acf_changed":true,"footnotes":""},"categories":[1],"tags":[163],"post_mwm_category":[242],"post_topic":[],"post_content_type":[],"post_duration":[],"post_actions":[],"post_franchise":[],"post_mwm_author":[272],"class_list":["post-12578","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-multimedia","post_mwm_category-arbeitsmarktanalysen","post_mwm_author-vsondergeld"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arbeitsmarkt Update Q1 2025: Abw\u00e4rtstrend auf dem Stellenmarkt beschleunigt sich - Indeed Hiring Lab Germany<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hiringlab.org\/de\/blog\/2025\/04\/14\/arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arbeitsmarkt Update Q1 2025: Abw\u00e4rtstrend auf dem Stellenmarkt beschleunigt sich - Indeed Hiring Lab Germany\" \/>\n<meta property=\"og:description\" content=\"Die Zahl der ausgeschriebenen Stellen auf Indeed in Deutschland ist im ersten Quartal 2025 um 7,2 Prozent zur\u00fcckgegangen. Damit hat sich der Abw\u00e4rtstrend der vergangenen Quartale noch einmal beschleunigt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hiringlab.org\/de\/blog\/2025\/04\/14\/arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich\/\" \/>\n<meta property=\"og:site_name\" content=\"Indeed Hiring Lab Germany\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-14T21:38:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-22T15:21:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hiringlab.org\/de\/wp-content\/uploads\/sites\/5\/2025\/03\/Devices-in-Use_Tablet_people-collaborating-open-office-laptop-tablet-gettyperp-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Virginia Sondergeld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/de\\\/blog\\\/2025\\\/04\\\/14\\\/arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/de\\\/blog\\\/2025\\\/04\\\/14\\\/arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich\\\/\"},\"author\":{\"name\":\"ltheissen\",\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/de\\\/#\\\/schema\\\/person\\\/4b5c7a64267b1cb495fb45e90277f353\"},\"headline\":\"Arbeitsmarkt Update Q1 2025: Abw\u00e4rtstrend auf dem Stellenmarkt beschleunigt sich\",\"datePublished\":\"2025-04-14T21:38:52+00:00\",\"dateModified\":\"2025-05-22T15:21:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/de\\\/blog\\\/2025\\\/04\\\/14\\\/arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich\\\/\"},\"wordCount\":1506,\"image\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/de\\\/blog\\\/2025\\\/04\\\/14\\\/arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d341ezm4iqaae0.cloudfront.net\\\/hiringlaborg\\\/sites\\\/5\\\/2025\\\/03\\\/02183016\\\/Devices-in-Use_Tablet_people-collaborating-open-office-laptop-tablet-gettyperp-1-scaled.jpg\",\"keywords\":[\"Multimedia\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/de\\\/blog\\\/2025\\\/04\\\/14\\\/arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich\\\/\",\"url\":\"https:\\\/\\\/www.hiringlab.org\\\/de\\\/blog\\\/2025\\\/04\\\/14\\\/arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich\\\/\",\"name\":\"Arbeitsmarkt Update Q1 2025: Abw\u00e4rtstrend auf dem Stellenmarkt beschleunigt sich - Indeed Hiring Lab Germany\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/de\\\/blog\\\/2025\\\/04\\\/14\\\/arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/de\\\/blog\\\/2025\\\/04\\\/14\\\/arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d341ezm4iqaae0.cloudfront.net\\\/hiringlaborg\\\/sites\\\/5\\\/2025\\\/03\\\/02183016\\\/Devices-in-Use_Tablet_people-collaborating-open-office-laptop-tablet-gettyperp-1-scaled.jpg\",\"datePublished\":\"2025-04-14T21:38:52+00:00\",\"dateModified\":\"2025-05-22T15:21:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/de\\\/#\\\/schema\\\/person\\\/4b5c7a64267b1cb495fb45e90277f353\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/de\\\/blog\\\/2025\\\/04\\\/14\\\/arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hiringlab.org\\\/de\\\/blog\\\/2025\\\/04\\\/14\\\/arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/de\\\/blog\\\/2025\\\/04\\\/14\\\/arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich\\\/#primaryimage\",\"url\":\"https:\\\/\\\/d341ezm4iqaae0.cloudfront.net\\\/hiringlaborg\\\/sites\\\/5\\\/2025\\\/03\\\/02183016\\\/Devices-in-Use_Tablet_people-collaborating-open-office-laptop-tablet-gettyperp-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/d341ezm4iqaae0.cloudfront.net\\\/hiringlaborg\\\/sites\\\/5\\\/2025\\\/03\\\/02183016\\\/Devices-in-Use_Tablet_people-collaborating-open-office-laptop-tablet-gettyperp-1-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Mitarbeiter arbeiten in einem Gro\u00dfraumb\u00fcro mit Laptops und Tablets\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/de\\\/blog\\\/2025\\\/04\\\/14\\\/arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hiringlab.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arbeitsmarkt Update Q1 2025: Abw\u00e4rtstrend auf dem Stellenmarkt beschleunigt sich\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.hiringlab.org\\\/de\\\/\",\"name\":\"Indeed Hiring Lab Germany\",\"description\":\"Just another Wordpress Admins Site Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hiringlab.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hiringlab.org\\\/de\\\/#\\\/schema\\\/person\\\/4b5c7a64267b1cb495fb45e90277f353\",\"name\":\"ltheissen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6367a954a4c7eb916945e225eca8caf2ceb055d42150b6a655ede10de2750ac2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6367a954a4c7eb916945e225eca8caf2ceb055d42150b6a655ede10de2750ac2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6367a954a4c7eb916945e225eca8caf2ceb055d42150b6a655ede10de2750ac2?s=96&d=mm&r=g\",\"caption\":\"ltheissen\"},\"url\":\"https:\\\/\\\/www.hiringlab.org\\\/de\\\/blog\\\/author\\\/ltheissen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arbeitsmarkt Update Q1 2025: Abw\u00e4rtstrend auf dem Stellenmarkt beschleunigt sich - Indeed Hiring Lab Germany","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hiringlab.org\/de\/blog\/2025\/04\/14\/arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich\/","og_locale":"de_DE","og_type":"article","og_title":"Arbeitsmarkt Update Q1 2025: Abw\u00e4rtstrend auf dem Stellenmarkt beschleunigt sich - Indeed Hiring Lab Germany","og_description":"Die Zahl der ausgeschriebenen Stellen auf Indeed in Deutschland ist im ersten Quartal 2025 um 7,2 Prozent zur\u00fcckgegangen. Damit hat sich der Abw\u00e4rtstrend der vergangenen Quartale noch einmal beschleunigt.","og_url":"https:\/\/www.hiringlab.org\/de\/blog\/2025\/04\/14\/arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich\/","og_site_name":"Indeed Hiring Lab Germany","article_published_time":"2025-04-14T21:38:52+00:00","article_modified_time":"2025-05-22T15:21:49+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.hiringlab.org\/de\/wp-content\/uploads\/sites\/5\/2025\/03\/Devices-in-Use_Tablet_people-collaborating-open-office-laptop-tablet-gettyperp-1-scaled.jpg","type":"image\/jpeg"}],"author":"Virginia Sondergeld","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hiringlab.org\/de\/blog\/2025\/04\/14\/arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich\/#article","isPartOf":{"@id":"https:\/\/www.hiringlab.org\/de\/blog\/2025\/04\/14\/arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich\/"},"author":{"name":"ltheissen","@id":"https:\/\/www.hiringlab.org\/de\/#\/schema\/person\/4b5c7a64267b1cb495fb45e90277f353"},"headline":"Arbeitsmarkt Update Q1 2025: Abw\u00e4rtstrend auf dem Stellenmarkt beschleunigt sich","datePublished":"2025-04-14T21:38:52+00:00","dateModified":"2025-05-22T15:21:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hiringlab.org\/de\/blog\/2025\/04\/14\/arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich\/"},"wordCount":1506,"image":{"@id":"https:\/\/www.hiringlab.org\/de\/blog\/2025\/04\/14\/arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich\/#primaryimage"},"thumbnailUrl":"https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/5\/2025\/03\/02183016\/Devices-in-Use_Tablet_people-collaborating-open-office-laptop-tablet-gettyperp-1-scaled.jpg","keywords":["Multimedia"],"articleSection":["Uncategorized"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.hiringlab.org\/de\/blog\/2025\/04\/14\/arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich\/","url":"https:\/\/www.hiringlab.org\/de\/blog\/2025\/04\/14\/arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich\/","name":"Arbeitsmarkt Update Q1 2025: Abw\u00e4rtstrend auf dem Stellenmarkt beschleunigt sich - Indeed Hiring Lab Germany","isPartOf":{"@id":"https:\/\/www.hiringlab.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hiringlab.org\/de\/blog\/2025\/04\/14\/arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich\/#primaryimage"},"image":{"@id":"https:\/\/www.hiringlab.org\/de\/blog\/2025\/04\/14\/arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich\/#primaryimage"},"thumbnailUrl":"https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/5\/2025\/03\/02183016\/Devices-in-Use_Tablet_people-collaborating-open-office-laptop-tablet-gettyperp-1-scaled.jpg","datePublished":"2025-04-14T21:38:52+00:00","dateModified":"2025-05-22T15:21:49+00:00","author":{"@id":"https:\/\/www.hiringlab.org\/de\/#\/schema\/person\/4b5c7a64267b1cb495fb45e90277f353"},"breadcrumb":{"@id":"https:\/\/www.hiringlab.org\/de\/blog\/2025\/04\/14\/arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hiringlab.org\/de\/blog\/2025\/04\/14\/arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.hiringlab.org\/de\/blog\/2025\/04\/14\/arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich\/#primaryimage","url":"https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/5\/2025\/03\/02183016\/Devices-in-Use_Tablet_people-collaborating-open-office-laptop-tablet-gettyperp-1-scaled.jpg","contentUrl":"https:\/\/d341ezm4iqaae0.cloudfront.net\/hiringlaborg\/sites\/5\/2025\/03\/02183016\/Devices-in-Use_Tablet_people-collaborating-open-office-laptop-tablet-gettyperp-1-scaled.jpg","width":2560,"height":1707,"caption":"Mitarbeiter arbeiten in einem Gro\u00dfraumb\u00fcro mit Laptops und Tablets"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hiringlab.org\/de\/blog\/2025\/04\/14\/arbeitsmarkt-update-q1-2025-abwaertstrend-auf-dem-stellenmarkt-beschleunigt-sich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hiringlab.org\/de\/"},{"@type":"ListItem","position":2,"name":"Arbeitsmarkt Update Q1 2025: Abw\u00e4rtstrend auf dem Stellenmarkt beschleunigt sich"}]},{"@type":"WebSite","@id":"https:\/\/www.hiringlab.org\/de\/#website","url":"https:\/\/www.hiringlab.org\/de\/","name":"Indeed Hiring Lab Germany","description":"Just another Wordpress Admins Site Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hiringlab.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/www.hiringlab.org\/de\/#\/schema\/person\/4b5c7a64267b1cb495fb45e90277f353","name":"ltheissen","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/6367a954a4c7eb916945e225eca8caf2ceb055d42150b6a655ede10de2750ac2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6367a954a4c7eb916945e225eca8caf2ceb055d42150b6a655ede10de2750ac2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6367a954a4c7eb916945e225eca8caf2ceb055d42150b6a655ede10de2750ac2?s=96&d=mm&r=g","caption":"ltheissen"},"url":"https:\/\/www.hiringlab.org\/de\/blog\/author\/ltheissen\/"}]}},"_links":{"self":[{"href":"https:\/\/www.hiringlab.org\/de\/wp-json\/wp\/v2\/posts\/12578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hiringlab.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hiringlab.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hiringlab.org\/de\/wp-json\/wp\/v2\/users\/103"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hiringlab.org\/de\/wp-json\/wp\/v2\/comments?post=12578"}],"version-history":[{"count":0,"href":"https:\/\/www.hiringlab.org\/de\/wp-json\/wp\/v2\/posts\/12578\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hiringlab.org\/de\/wp-json\/wp\/v2\/media\/12570"}],"wp:attachment":[{"href":"https:\/\/www.hiringlab.org\/de\/wp-json\/wp\/v2\/media?parent=12578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hiringlab.org\/de\/wp-json\/wp\/v2\/categories?post=12578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hiringlab.org\/de\/wp-json\/wp\/v2\/tags?post=12578"},{"taxonomy":"post_mwm_category","embeddable":true,"href":"https:\/\/www.hiringlab.org\/de\/wp-json\/wp\/v2\/post_mwm_category?post=12578"},{"taxonomy":"post_topic","embeddable":true,"href":"https:\/\/www.hiringlab.org\/de\/wp-json\/wp\/v2\/post_topic?post=12578"},{"taxonomy":"post_content_type","embeddable":true,"href":"https:\/\/www.hiringlab.org\/de\/wp-json\/wp\/v2\/post_content_type?post=12578"},{"taxonomy":"post_duration","embeddable":true,"href":"https:\/\/www.hiringlab.org\/de\/wp-json\/wp\/v2\/post_duration?post=12578"},{"taxonomy":"post_actions","embeddable":true,"href":"https:\/\/www.hiringlab.org\/de\/wp-json\/wp\/v2\/post_actions?post=12578"},{"taxonomy":"post_franchise","embeddable":true,"href":"https:\/\/www.hiringlab.org\/de\/wp-json\/wp\/v2\/post_franchise?post=12578"},{"taxonomy":"post_mwm_author","embeddable":true,"href":"https:\/\/www.hiringlab.org\/de\/wp-json\/wp\/v2\/post_mwm_author?post=12578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}